{"id":81618,"date":"2026-03-19T09:45:38","date_gmt":"2026-03-19T09:45:38","guid":{"rendered":"https:\/\/transportjournal.com\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/"},"modified":"2026-03-19T09:45:38","modified_gmt":"2026-03-19T09:45:38","slug":"mercedes-benz-testa-sistema-de-carregamento-megawatt","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/","title":{"rendered":"Mercedes-Benz testa sistema de carregamento Megawatt"},"content":{"rendered":"<p>Durante um extenso teste, engenheiros de desenvolvimento da Mercedes-Benz Trucks avaliaram a capacidade do Megawatt Charging System (MCS) com o novo eActros 600. O teste, realizado no in\u00edcio do ano, abrangeu cerca de 2.400 km e percorreu a Alemanha, Pa\u00edses Baixos, B\u00e9lgica e Dinamarca at\u00e9 a Su\u00e9cia. O objetivo foi verificar a compatibilidade entre os ve\u00edculos e as esta\u00e7\u00f5es de carregamento MCS de diferentes fabricantes, al\u00e9m de testar a viabilidade pr\u00e1tica do carregamento em condi\u00e7\u00f5es de inverno.<\/p>\n<p>Os ve\u00edculos de teste foram carregados em v\u00e1rias esta\u00e7\u00f5es de carregamento, tanto p\u00fablicas quanto privadas. Um eActros 600 tamb\u00e9m realizou testes adicionais de inverno no C\u00edrculo Polar \u00c1rtico finland\u00eas, onde as temperaturas chegaram a -20 \u00b0C, antes de iniciar o caminho de volta.<\/p>\n<h3>Descobertas dos Testes<\/h3>\n<p>Peter Ziegler, chefe de Componentes de E-Carregamento da Mercedes-Benz Trucks, explica as principais descobertas dos testes. Estes forneceram informa\u00e7\u00f5es importantes sobre a gest\u00e3o t\u00e9rmica da bateria e a interoperabilidade entre o ve\u00edculo e a infraestrutura de carregamento. Os testes confirmaram que pot\u00eancias de carregamento na faixa de megawatt s\u00e3o poss\u00edveis mesmo em temperaturas baixas, desde que a bateria mantenha uma temperatura de opera\u00e7\u00e3o adequada. Isso \u00e9 especialmente relevante, pois o carregamento em megawatt geralmente ocorre durante as pausas obrigat\u00f3rias de dire\u00e7\u00e3o, garantindo a viabilidade operacional no uso real. Al\u00e9m disso, foram realizados com sucesso v\u00e1rios processos de carregamento em diferentes pontos de carregamento, comprovando a viabilidade pr\u00e1tica do sistema.<\/p>\n<h3>Potencial do Carregamento em Megawatt<\/h3>\n<p>A Mercedes-Benz Trucks v\u00ea no carregamento em megawatt um papel central para a eletrifica\u00e7\u00e3o do transporte rodovi\u00e1rio pesado e apoia o padr\u00e3o MCS como uma solu\u00e7\u00e3o aberta e intercompat\u00edvel entre fabricantes. Dada a din\u00e2mica do mercado de ve\u00edculos comerciais el\u00e9tricos a bateria, um padr\u00e3o de carregamento uniforme e internacionalmente compat\u00edvel \u00e9 considerado cada vez mais importante. O padr\u00e3o MCS deve promover a interoperabilidade, escalabilidade e seguran\u00e7a de investimento entre diferentes mercados e fabricantes.<\/p>\n<h3>Pr\u00f3ximos Passos para a Finaliza\u00e7\u00e3o do Padr\u00e3o MCS<\/h3>\n<p>A finaliza\u00e7\u00e3o em andamento do padr\u00e3o MCS abrange tanto o hardware quanto o software dos ve\u00edculos e da infraestrutura de carregamento. Nos pr\u00f3ximos meses, a Mercedes-Benz Trucks planeja novos testes de interoperabilidade com diferentes fabricantes de esta\u00e7\u00f5es de carregamento, a fim de otimizar ainda mais a intera\u00e7\u00e3o entre o ve\u00edculo e a infraestrutura de carregamento.<\/p>\n<p>Al\u00e9m disso, a Daimler Truck participa como parceiro da ind\u00fastria no projeto &#8222;HoLa Carregamento de Alta Performance no Transporte Rodovi\u00e1rio&#8220; e testar\u00e1 o eActros 600 na infraestrutura de carregamento de alta performance em opera\u00e7\u00e3o real ao longo do ano. Na segunda metade do ano, est\u00e3o previstas as primeiras provas com clientes dos eActros 600 compat\u00edveis com MCS em opera\u00e7\u00f5es log\u00edsticas reais. Esses ve\u00edculos ser\u00e3o utilizados no projeto de eletrifica\u00e7\u00e3o da log\u00edstica de transporte das f\u00e1bricas da Mercedes-Benz Trucks na Alemanha, &#8222;Electrify Inbound Logistic&#8220;, em diversos clientes. Para reduzir os tempos de carregamento dos caminh\u00f5es el\u00e9tricos, uma esta\u00e7\u00e3o de carregamento compat\u00edvel com MCS est\u00e1 planejada para o terreno da f\u00e1brica em W\u00f6rth am Rhein, que dever\u00e1 entrar em opera\u00e7\u00e3o a partir da metade do ano.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.daimlertruck.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.daimlertruck.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercedes-Benz Trucks testou com sucesso o sistema de carregamento Megawatt com o eActros 600, para verificar a viabilidade pr\u00e1tica e a interoperabilidade em condi\u00e7\u00f5es de inverno.<\/p>\n","protected":false},"author":12,"featured_media":81613,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9092,1623,1616],"tags":[29274,29275,29276,29277,29278,29279,29280,29281,29282,29283,29284,29285,15689,29286,29287,29288,29289,29290,29291,29292,29293,29294,29295,29296,29297,29298,29299,29300,29301,29302,29303,29304,29305,29306,29307,29308,29309,29310,15704,29311,29312,29313,29314,29315,29316,29317,29318,29319,29320,29321,29322,29323,29324,29325,29326,29327],"class_list":["post-81618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-europa","category-intermodal-rodoviario","tag-batteriewaermemanagement","tag-battery-thermal-management","tag-camions-a-charge-haute-performance","tag-charge-megawatt-conditions-hivernales","tag-charging-infrastructure-optimization","tag-charging-points-winter-test","tag-charging-processes-practicality","tag-charging-station-manufacturers","tag-daimler-truck-project","tag-daimler-truck-projekt","tag-deutsch-megawatt-ladesystem","tag-driving-time-breaks","tag-eactros-600","tag-electrification-inbound-logistics","tag-electrification-logistique-entrante","tag-electrification-long-haul-transport","tag-electrification-transport-longue-distance","tag-elektrifizierung-fernverkehr","tag-elektrifizierung-inbound-logistic","tag-essai-routier-allemagne","tag-fabricants-de-stations-de-charge","tag-gestion-thermique-des-batteries","tag-high-performance-charging-trucks","tag-hochleistungsladen-lkw","tag-interoperabilitaet-ladeinfrastruktur","tag-interoperabilite-infrastructure-de-charge","tag-interoperability-charging-infrastructure","tag-ladeinfrastruktur-optimierung","tag-ladepunkte-wintertest","tag-ladesaeulenhersteller","tag-ladevorgaenge-praxistauglichkeit","tag-lenkzeitpausen","tag-logistique-de-transport-allemagne","tag-mcs-capable-vehicles","tag-mcs-faehige-fahrzeuge","tag-mcs-standard","tag-megawatt-charging-winter-conditions-francais-systeme-de-charge-megawatt","tag-megawattladen-winterbedingungen-english-megawatt-charging-system","tag-mercedes-benz-trucks","tag-norme-mcs","tag-oeffentliche-ladesaeulen","tag-optimisation-de-linfrastructure-de-charge","tag-pauses-de-conduite","tag-points-de-charge-test-hivernal","tag-private-charging-stations","tag-private-ladesaeulen","tag-processus-de-charge-praticite","tag-projet-daimler-truck","tag-public-charging-stations","tag-stations-de-charge-privees","tag-stations-de-charge-publiques","tag-test-drive-germany","tag-testfahrt-deutschland","tag-transport-logistics-germany","tag-transportlogistik-deutschland","tag-vehicules-compatibles-mcs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercedes-Benz testa sistema de carregamento Megawatt - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercedes-Benz testa sistema de carregamento Megawatt - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Mercedes-Benz Trucks testou com sucesso o sistema de carregamento Megawatt com o eActros 600, para verificar a viabilidade pr\u00e1tica e a interoperabilidade em condi\u00e7\u00f5es de inverno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T09:45:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/03\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1138\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"Mercedes-Benz testa sistema de carregamento Megawatt\",\"datePublished\":\"2026-03-19T09:45:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg\",\"keywords\":[\"Batteriew\u00e4rmemanagement\",\"battery thermal management\",\"camions \u00e0 charge haute performance\",\"charge Megawatt conditions hivernales\",\"charging infrastructure optimization\",\"charging points winter test\",\"charging processes practicality\",\"charging station manufacturers\",\"Daimler Truck project\",\"Daimler Truck Projekt\",\"Deutsch Megawatt-Ladesystem\",\"driving time breaks\",\"eActros 600\",\"electrification inbound logistics\",\"\u00e9lectrification logistique entrante\",\"electrification long-haul transport\",\"\u00e9lectrification transport longue distance\",\"Elektrifizierung Fernverkehr\",\"Elektrifizierung Inbound Logistic\",\"essai routier Allemagne\",\"fabricants de stations de charge\",\"gestion thermique des batteries\",\"high-performance charging trucks\",\"Hochleistungsladen Lkw\",\"Interoperabilit\u00e4t Ladeinfrastruktur\",\"interop\u00e9rabilit\u00e9 infrastructure de charge\",\"interoperability charging infrastructure\",\"Ladeinfrastruktur Optimierung\",\"Ladepunkte Wintertest\",\"Lades\u00e4ulenhersteller\",\"Ladevorg\u00e4nge Praxistauglichkeit\",\"Lenkzeitpausen\",\"logistique de transport Allemagne\",\"MCS-capable vehicles\",\"MCS-f\u00e4hige Fahrzeuge\",\"MCS-Standard\",\"megawatt charging winter conditions Fran\u00e7ais Syst\u00e8me de charge Megawatt\",\"Megawattladen Winterbedingungen English Megawatt charging system\",\"Mercedes-Benz Trucks\",\"norme MCS\",\"\u00f6ffentliche Lades\u00e4ulen\",\"optimisation de l'infrastructure de charge\",\"pauses de conduite\",\"points de charge test hivernal\",\"private charging stations\",\"private Lades\u00e4ulen\",\"processus de charge praticit\u00e9\",\"projet Daimler Truck\",\"public charging stations\",\"stations de charge priv\u00e9es\",\"stations de charge publiques\",\"test drive Germany\",\"Testfahrt Deutschland\",\"transport logistics Germany\",\"Transportlogistik Deutschland\",\"v\u00e9hicules compatibles MCS\"],\"articleSection\":[\"Deutschland\",\"Europa\",\"Intermodal \\\/ Rodovi\u00e1rio\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/\",\"name\":\"Mercedes-Benz testa sistema de carregamento Megawatt - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg\",\"datePublished\":\"2026-03-19T09:45:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg\",\"width\":1138,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/03\\\/19\\\/mercedes-benz-testa-sistema-de-carregamento-megawatt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercedes-Benz testa sistema de carregamento Megawatt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercedes-Benz testa sistema de carregamento Megawatt - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/","og_locale":"pt_PT","og_type":"article","og_title":"Mercedes-Benz testa sistema de carregamento Megawatt - ITJ | International Transport Journal","og_description":"Mercedes-Benz Trucks testou com sucesso o sistema de carregamento Megawatt com o eActros 600, para verificar a viabilidade pr\u00e1tica e a interoperabilidade em condi\u00e7\u00f5es de inverno.","og_url":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2026-03-19T09:45:38+00:00","og_image":[{"width":1138,"height":640,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/03\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg","type":"image\/jpeg"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andreas Haug","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"Mercedes-Benz testa sistema de carregamento Megawatt","datePublished":"2026-03-19T09:45:38+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/03\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg","keywords":["Batteriew\u00e4rmemanagement","battery thermal management","camions \u00e0 charge haute performance","charge Megawatt conditions hivernales","charging infrastructure optimization","charging points winter test","charging processes practicality","charging station manufacturers","Daimler Truck project","Daimler Truck Projekt","Deutsch Megawatt-Ladesystem","driving time breaks","eActros 600","electrification inbound logistics","\u00e9lectrification logistique entrante","electrification long-haul transport","\u00e9lectrification transport longue distance","Elektrifizierung Fernverkehr","Elektrifizierung Inbound Logistic","essai routier Allemagne","fabricants de stations de charge","gestion thermique des batteries","high-performance charging trucks","Hochleistungsladen Lkw","Interoperabilit\u00e4t Ladeinfrastruktur","interop\u00e9rabilit\u00e9 infrastructure de charge","interoperability charging infrastructure","Ladeinfrastruktur Optimierung","Ladepunkte Wintertest","Lades\u00e4ulenhersteller","Ladevorg\u00e4nge Praxistauglichkeit","Lenkzeitpausen","logistique de transport Allemagne","MCS-capable vehicles","MCS-f\u00e4hige Fahrzeuge","MCS-Standard","megawatt charging winter conditions Fran\u00e7ais Syst\u00e8me de charge Megawatt","Megawattladen Winterbedingungen English Megawatt charging system","Mercedes-Benz Trucks","norme MCS","\u00f6ffentliche Lades\u00e4ulen","optimisation de l'infrastructure de charge","pauses de conduite","points de charge test hivernal","private charging stations","private Lades\u00e4ulen","processus de charge praticit\u00e9","projet Daimler Truck","public charging stations","stations de charge priv\u00e9es","stations de charge publiques","test drive Germany","Testfahrt Deutschland","transport logistics Germany","Transportlogistik Deutschland","v\u00e9hicules compatibles MCS"],"articleSection":["Deutschland","Europa","Intermodal \/ Rodovi\u00e1rio"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/","url":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/","name":"Mercedes-Benz testa sistema de carregamento Megawatt - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/03\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg","datePublished":"2026-03-19T09:45:38+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/03\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/03\/Daimler-Truck-csm_cms_ff8a87f117-aspect-ratio-1400-788.jpg","width":1138,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/03\/19\/mercedes-benz-testa-sistema-de-carregamento-megawatt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Mercedes-Benz testa sistema de carregamento Megawatt"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/pt-pt\/#website","url":"https:\/\/transportjournal.com\/pt-pt\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/pt-pt\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/transportjournal.com\/pt-pt\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/81618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=81618"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/81618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/media\/81613"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=81618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=81618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=81618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}