{"id":76445,"date":"2026-02-10T11:31:12","date_gmt":"2026-02-10T11:31:12","guid":{"rendered":"https:\/\/transportjournal.com\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/"},"modified":"2026-02-10T11:31:12","modified_gmt":"2026-02-10T11:31:12","slug":"joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/","title":{"rendered":"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga"},"content":{"rendered":"<p>Joramco assinou recentemente dois contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga internacionais, que consolidam ainda mais a posi\u00e7\u00e3o da empresa no setor de manuten\u00e7\u00e3o de aeronaves. Os acordos foram anunciados durante a MRO Middle East 2026 em Dubai e incluem servi\u00e7os abrangentes de manuten\u00e7\u00e3o para as frotas de aeronaves da mas, uma importante companhia a\u00e9rea de carga mexicana, e da ULS Airlines Cargo, da Turquia.<\/p>\n<h3>Contrato de manuten\u00e7\u00e3o com mas<\/h3>\n<p>No primeiro passo, a Joramco, empresa de manuten\u00e7\u00e3o, reparo e revis\u00e3o de aeronaves com sede em Am\u00e3, realizar\u00e1 extensos trabalhos de manuten\u00e7\u00e3o na frota A330 da mas. Esses trabalhos est\u00e3o programados para o ano de 2026. Adam Voss, o CEO da Joramco, comentou sobre este contrato e enfatizou a import\u00e2ncia da colabora\u00e7\u00e3o: \u201cEstamos felizes em receber mais aeronaves da mas na Joramco. Este acordo reafirma a posi\u00e7\u00e3o da Joramco como um fornecedor global de MRO confi\u00e1vel.\u201d<\/p>\n<h3>Parceria com ULS Airlines Cargo<\/h3>\n<p>Al\u00e9m disso, a Joramco assinou um novo contrato de manuten\u00e7\u00e3o com a ULS Airlines Cargo. No \u00e2mbito deste acordo, a Joramco fornecer\u00e1 servi\u00e7os de manuten\u00e7\u00e3o para as aeronaves A310 da companhia a\u00e9rea turca. Esta parceria reflete a confian\u00e7a cont\u00ednua de operadores regionais e internacionais nas capacidades t\u00e9cnicas e na confiabilidade da Joramco. Voss tamb\u00e9m comentou sobre este acordo e destacou: \u201cEste acordo com a ULS Airlines Cargo \u00e9 uma forte confirma\u00e7\u00e3o da expertise da Joramco em apoiar opera\u00e7\u00f5es de carga especializadas. \u00c0 medida que o setor de carga a\u00e9rea desempenha um papel crucial nas cadeias de suprimento globais, os operadores est\u00e3o cada vez mais em busca de parceiros de MRO que combinem know-how t\u00e9cnico com flexibilidade operacional.\u201d<\/p>\n<p>Os novos contratos sublinham o compromisso da Joramco com a qualidade e a seguran\u00e7a na manuten\u00e7\u00e3o de aeronaves e fortalecem a posi\u00e7\u00e3o da empresa como um fornecedor l\u00edder na regi\u00e3o do Oriente M\u00e9dio.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.joramco.com.jo\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.joramco.com.jo<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joramco assinou dois contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas internacionais de carga para fortalecer sua posi\u00e7\u00e3o na manuten\u00e7\u00e3o de aeronaves no Oriente M\u00e9dio.<\/p>\n","protected":false},"author":12,"featured_media":76440,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1626,1623,1624,1618],"tags":[],"class_list":["post-76445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-americas","category-europa","category-medio-oriente","category-transporte-aereo-de-mercadorias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Joramco assinou dois contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas internacionais de carga para fortalecer sua posi\u00e7\u00e3o na manuten\u00e7\u00e3o de aeronaves no Oriente M\u00e9dio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T11:31:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga\",\"datePublished\":\"2026-02-10T11:31:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"articleSection\":[\"Am\u00e9ricas\",\"Europa\",\"M\u00e9dio Oriente\",\"Transporte a\u00e9reo de mercadorias\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/\",\"name\":\"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"datePublished\":\"2026-02-10T11:31:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"width\":2560,\"height\":1441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2026\\\/02\\\/10\\\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/","og_locale":"pt_PT","og_type":"article","og_title":"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga - ITJ | International Transport Journal","og_description":"Joramco assinou dois contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas internacionais de carga para fortalecer sua posi\u00e7\u00e3o na manuten\u00e7\u00e3o de aeronaves no Oriente M\u00e9dio.","og_url":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2026-02-10T11:31:12+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg","type":"image\/jpeg"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andreas Haug","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga","datePublished":"2026-02-10T11:31:12+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg","articleSection":["Am\u00e9ricas","Europa","M\u00e9dio Oriente","Transporte a\u00e9reo de mercadorias"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/","url":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/","name":"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg","datePublished":"2026-02-10T11:31:12+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/Joramco-mas-Copy-of-9M6A0746_0-scaled-aspect-ratio-1400-788-scaled-1.jpg","width":2560,"height":1441},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/pt-pt\/2026\/02\/10\/joramco-garante-contratos-de-manutencao-com-companhias-aereas-de-carga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Joramco garante contratos de manuten\u00e7\u00e3o com companhias a\u00e9reas de carga"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/pt-pt\/#website","url":"https:\/\/transportjournal.com\/pt-pt\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/pt-pt\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/transportjournal.com\/pt-pt\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/76445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=76445"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/76445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/media\/76440"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=76445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=76445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=76445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}