{"id":17344,"date":"2020-04-08T15:34:32","date_gmt":"2020-04-08T13:34:32","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/"},"modified":"2025-12-15T12:26:54","modified_gmt":"2025-12-15T11:26:54","slug":"witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/","title":{"rendered":"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg"},"content":{"rendered":"<p>O varejista de alimentos REWE come\u00e7ar\u00e1 a abastecer mais de 350 filiais no norte da Alemanha a partir de agosto de 2022 a partir de seu novo centro log\u00edstico automatizado em Henstedt-Ulzburg. O contrato para o planejamento e a realiza\u00e7\u00e3o foi concedido ao empreiteiro geral WITRON Logistik + Informatik GmbH de Parkstein.<\/p>\n<p>(Parkstein, 08.04.2020) O empreiteiro geral Witron assumir\u00e1 o planejamento e a execu\u00e7\u00e3o de um novo centro log\u00edstico automatizado para o varejista de alimentos em Henstedt-Ulzburg.<\/p>\n<p>Com as solu\u00e7\u00f5es WITRON OPM (Order Picking Machinery), DPS (Dynamic Picking System), CPS (Car Picking System) e DPP (Display Pallet Picking), at\u00e9 165.000 unidades comerciais podem ser coletadas de forma adequada para as filiais em um dia de pico. Na instala\u00e7\u00e3o de 86.500 m<sup>2<\/sup>, mais de 12.000 artigos diferentes dos sortimentos secos e frescos s\u00e3o armazenados.<\/p>\n<p>&#8220;Os principais crit\u00e9rios de decis\u00e3o para o investimento foram tanto aspectos econ\u00f4micos quanto ecol\u00f3gicos&#8221;, diz Lars Siebel, chefe de log\u00edstica nacional \/ gerenciamento da cadeia de suprimentos da REWE. &#8220;Isso inclui, em particular, uma alta rentabilidade ao longo da cadeia de suprimentos, bem como a garantia a longo prazo de um excelente abastecimento de nossos mercados, mesmo em tempos de crise. Nossa estrat\u00e9gia de sustentabilidade tamb\u00e9m \u00e9 refor\u00e7ada por outros aspectos \u2013 como, por exemplo, locais de trabalho ergon\u00f4micos, a redu\u00e7\u00e3o das emiss\u00f5es de CO<sub>2<\/sub> por meio de cargas otimizadas e, consequentemente, a redu\u00e7\u00e3o das viagens de caminh\u00e3o. E, por \u00faltimo, mas n\u00e3o menos importante, a constru\u00e7\u00e3o do local de armazenamento e administra\u00e7\u00e3o de acordo com os padr\u00f5es de ouro da DGNB.&#8221;  <\/p>\n<p>Foto: Witron<\/p>\n<p><a href=\"https:\/\/www.witron.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.witron.de\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O varejista de alimentos REWE come\u00e7ar\u00e1 a abastecer mais de 350 filiais no norte da Alemanha a partir de agosto de 2022 a partir de seu<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-17344","post","type-post","status-publish","format-standard","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"O varejista de alimentos REWE come\u00e7ar\u00e1 a abastecer mais de 350 filiais no norte da Alemanha a partir de agosto de 2022 a partir de seu [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-08T13:34:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:26:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg\",\"datePublished\":\"2020-04-08T13:34:32+00:00\",\"dateModified\":\"2025-12-15T11:26:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/\",\"name\":\"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2020-04-08T13:34:32+00:00\",\"dateModified\":\"2025-12-15T11:26:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/04\\\/08\\\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/","og_locale":"pt_PT","og_type":"article","og_title":"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg - ITJ | International Transport Journal","og_description":"O varejista de alimentos REWE come\u00e7ar\u00e1 a abastecer mais de 350 filiais no norte da Alemanha a partir de agosto de 2022 a partir de seu [\u2026]","og_url":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-04-08T13:34:32+00:00","article_modified_time":"2025-12-15T11:26:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/"},"author":{"name":"","@id":""},"headline":"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg","datePublished":"2020-04-08T13:34:32+00:00","dateModified":"2025-12-15T11:26:54+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"articleSection":["Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/","url":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/","name":"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#website"},"datePublished":"2020-04-08T13:34:32+00:00","dateModified":"2025-12-15T11:26:54+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/04\/08\/witron-realiza-centro-logistico-da-rewe-em-henstedt-ulzburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"WITRON realiza centro log\u00edstico da REWE em Henstedt-Ulzburg"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/pt-pt\/#website","url":"https:\/\/transportjournal.com\/pt-pt\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/pt-pt\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=17344"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17344\/revisions"}],"predecessor-version":[{"id":31038,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17344\/revisions\/31038"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=17344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=17344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=17344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}