{"id":17119,"date":"2020-02-13T06:21:41","date_gmt":"2020-02-13T05:21:41","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/"},"modified":"2025-12-15T12:26:08","modified_gmt":"2025-12-15T11:26:08","slug":"hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/","title":{"rendered":"HHLA Hamburg atinge os objetivos no ano fiscal de 2019"},"content":{"rendered":"<p>A HHLA Hamburg atinge os objetivos no ano fiscal de 2019. Receita e resultado operacional (EBIT) aumentam. Aumento moderado no manuseio de cont\u00eaineres, aumento significativo no volume de transporte<\/p>\n<p>(Hamburgo, 13.02.2020) A Hamburger Hafen und Logistik AG (HHLA) aumentou sua receita consolidada em 6,8 por cento, alcan\u00e7ando 1,38 bilh\u00f5es de euros (no ano anterior: 1,29 bilh\u00f5es de euros) no ano fiscal de 2019, de acordo com n\u00fameros preliminares ainda n\u00e3o auditados. O resultado operacional (EBIT) do grupo foi de 222 milh\u00f5es de euros (no ano anterior: 204 milh\u00f5es de euros), um crescimento de 8,8 por cento. O segmento de log\u00edstica portu\u00e1ria, listado em bolsa, gerou receitas de 1,35 bilh\u00f5es de euros (no ano anterior: 1,26 bilh\u00f5es de euros) e um resultado operacional (EBIT) de 205 milh\u00f5es de euros (no ano anterior: 188 milh\u00f5es de euros).Nos terminais de cont\u00eaineres da HHLA, foram manuseados um total de 7,6 milh\u00f5es de cont\u00eaineres padr\u00e3o (TEU) no ano fiscal de 2019. Isso representa um aumento de 3,3 por cento em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior (7,3 milh\u00f5es de TEU). O manuseio de cont\u00eaineres nos tr\u00eas terminais de cont\u00eaineres de Hamburgo conseguiu ligeiramente superar o alto n\u00edvel do ano anterior, enquanto o manuseio nos terminais internacionais da HHLA em Odessa (Ucr\u00e2nia) e Tallinn (Est\u00f4nia) ficou muito acima do n\u00edvel do ano anterior. Os n\u00fameros do ano anterior s\u00e3o apenas parcialmente compar\u00e1veis, pois o terminal de cont\u00eaineres em Tallinn foi incorporado ao grupo de consolida\u00e7\u00e3o da HHLA apenas no final do segundo trimestre de 2018. As atividades intermodais da HHLA superaram o forte resultado do ano anterior com um volume de transporte de 1,57 milh\u00f5es de TEU (no ano anterior: 1,48 milh\u00f5es de TEU), um aumento de 5,7 por cento. Esse resultado foi impulsionado tanto pelo transporte ferrovi\u00e1rio quanto pelo transporte rodovi\u00e1rio.<\/p>\n<p>Foto: HHLA \/ Thies R\u00e4tzke<\/p>\n<p>https:\/\/hhla.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A HHLA Hamburg atinge os objetivos no ano fiscal de 2019. Receita e resultado operacional (EBIT) aumentam. Aumento moderado no manuseio de cont\u00eaineres, aumento significativo no<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-17119","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HHLA Hamburg atinge os objetivos no ano fiscal de 2019 - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HHLA Hamburg atinge os objetivos no ano fiscal de 2019 - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"A HHLA Hamburg atinge os objetivos no ano fiscal de 2019. Receita e resultado operacional (EBIT) aumentam. Aumento moderado no manuseio de cont\u00eaineres, aumento significativo no [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-13T05:21:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:26:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"HHLA Hamburg atinge os objetivos no ano fiscal de 2019\",\"datePublished\":\"2020-02-13T05:21:41+00:00\",\"dateModified\":\"2025-12-15T11:26:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/\",\"name\":\"HHLA Hamburg atinge os objetivos no ano fiscal de 2019 - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2020-02-13T05:21:41+00:00\",\"dateModified\":\"2025-12-15T11:26:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/2020\\\/02\\\/13\\\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HHLA Hamburg atinge os objetivos no ano fiscal de 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HHLA Hamburg atinge os objetivos no ano fiscal de 2019 - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/","og_locale":"pt_PT","og_type":"article","og_title":"HHLA Hamburg atinge os objetivos no ano fiscal de 2019 - ITJ | International Transport Journal","og_description":"A HHLA Hamburg atinge os objetivos no ano fiscal de 2019. Receita e resultado operacional (EBIT) aumentam. Aumento moderado no manuseio de cont\u00eaineres, aumento significativo no [\u2026]","og_url":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-02-13T05:21:41+00:00","article_modified_time":"2025-12-15T11:26:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/"},"author":{"name":"","@id":""},"headline":"HHLA Hamburg atinge os objetivos no ano fiscal de 2019","datePublished":"2020-02-13T05:21:41+00:00","dateModified":"2025-12-15T11:26:08+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/","url":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/","name":"HHLA Hamburg atinge os objetivos no ano fiscal de 2019 - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#website"},"datePublished":"2020-02-13T05:21:41+00:00","dateModified":"2025-12-15T11:26:08+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/pt-pt\/2020\/02\/13\/hhla-hamburg-atinge-os-objetivos-no-ano-fiscal-de-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"HHLA Hamburg atinge os objetivos no ano fiscal de 2019"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/pt-pt\/#website","url":"https:\/\/transportjournal.com\/pt-pt\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/pt-pt\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=17119"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17119\/revisions"}],"predecessor-version":[{"id":30635,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17119\/revisions\/30635"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=17119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=17119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=17119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}