{"id":17088,"date":"2020-02-06T06:34:44","date_gmt":"2020-02-06T05:34:44","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/"},"modified":"2025-12-15T12:26:01","modified_gmt":"2025-12-15T11:26:01","slug":"hoyer-group-bereikt-50-000ste-ibc-container","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/","title":{"rendered":"HOYER Group bereikt 50.000ste IBC-container"},"content":{"rendered":"<p>De HOYER Group heeft met de 50.000ste Intermediate Bulk Container (IBC) een nieuwe mijlpaal bereikt. De roestvrijstalen containers worden gebruikt voor veeleisende producten in de voedings-, chemische en cosmetica-industrie. In slechts vijf jaar is de IBC-vloot van de Hoyer Group meer dan verdubbeld.<\/p>\n<p>(Hamburg, 06.02.2020) De Hoyer Group is gespecialiseerd in het transport en de handling van vloeibare goederen. IBC&#8217;s worden wereldwijd gebruikt voor zowel het transport als de opslag van veeleisende chemische producten en voedingsmiddelen. Ze hebben een capaciteit van 500 tot 1.110 liter en worden vooral gebruikt door de voedings-, chemische en cosmetica-industrie in China, Europa en de VS. Aan het einde van het jaar bereikte de IBC-vloot een mijlpaal van 50.000 eenheden. Vooral verwarmbare IBC&#8217;s voor de voedingsindustrie, cilindrische containers voor de verf- en lakindustrie en drukcontainers, zogenaamde Mini Pressure Tanks (MPT), voor speciale chemicali\u00ebn zijn zeer gewild.De robuuste roestvrijstalen containers zorgen ook bij langdurig gebruik voor een constante productkwaliteit, hebben een langere levensduur dan plastic containers en zijn bovendien duurzaam in de gebruikscyclus. Hoyer beschikt over een wereldwijd netwerk dat een steriele reiniging van de containers aanbiedt. Dit garandeert een hogere productveiligheid en -zuiverheid \u2013 een service die vooral in de voedingssector zeer gewild is.&#8221;De eisen aan de uitrusting van de IBC&#8217;s nemen toe. Hierop reageren we niet alleen met de juiste apparatuur, maar ook met uitgebreide diensten die de kwaliteit en veiligheid van het product waarborgen, evenals een effici\u00ebnte planning en levering. Met onze vloot kunnen we flexibel inspelen op de behoeften van onze klanten,&#8221; aldus Stephanie Muhs, Director IBC Logistics bij de HOYER Group.Over de Hoyer Group: Hoyer is sinds 1946 als traditioneel, onafhankelijk familiebedrijf een van de toonaangevende bulklogistiekers ter wereld en beschikt als specialist over uitgebreide knowhow in complexe diensten en een bijzondere klantgerichtheid. In de Europese en wereldwijde bulklogistiek worden uitgebreide oplossingen ontwikkeld en gerealiseerd, met name voor de sectoren chemie, voeding, gas en minerale olie. Ongeveer 6.200 medewerkers in meer dan 115 landen ondersteunen klanten om in hun respectieve markten nog succesvoller te zijn met doordachte logistieke oplossingen. HOYER beschikt over ongeveer 2.200 trekkers, 2.300 tanktrailers, 50.000 IBC&#8217;s, 40.300 tankcontainers en talrijke logistieke faciliteiten met depots, reinigingsinstallaties en werkplaatsen. www.Hoyer-group.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De HOYER Group heeft met de 50.000ste Intermediate Bulk Container (IBC) een nieuwe mijlpaal bereikt. De roestvrijstalen containers worden gebruikt voor veeleisende producten in de voedings-,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-17088","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HOYER Group bereikt 50.000ste IBC-container - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HOYER Group bereikt 50.000ste IBC-container - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"De HOYER Group heeft met de 50.000ste Intermediate Bulk Container (IBC) een nieuwe mijlpaal bereikt. De roestvrijstalen containers worden gebruikt voor veeleisende producten in de voedings-, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-06T05:34:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:26:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"HOYER Group bereikt 50.000ste IBC-container\",\"datePublished\":\"2020-02-06T05:34:44+00:00\",\"dateModified\":\"2025-12-15T11:26:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/\"},\"wordCount\":364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/\",\"name\":\"HOYER Group bereikt 50.000ste IBC-container - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/#website\"},\"datePublished\":\"2020-02-06T05:34:44+00:00\",\"dateModified\":\"2025-12-15T11:26:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/2020\\\/02\\\/06\\\/hoyer-group-bereikt-50-000ste-ibc-container\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HOYER Group bereikt 50.000ste IBC-container\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/#organization\",\"name\":\"Logismedia Groep AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Groep AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HOYER Group bereikt 50.000ste IBC-container - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/","og_locale":"nl_NL","og_type":"article","og_title":"HOYER Group bereikt 50.000ste IBC-container - ITJ | International Transport Journal","og_description":"De HOYER Group heeft met de 50.000ste Intermediate Bulk Container (IBC) een nieuwe mijlpaal bereikt. De roestvrijstalen containers worden gebruikt voor veeleisende producten in de voedings-, [\u2026]","og_url":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-02-06T05:34:44+00:00","article_modified_time":"2025-12-15T11:26:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/"},"author":{"name":"","@id":""},"headline":"HOYER Group bereikt 50.000ste IBC-container","datePublished":"2020-02-06T05:34:44+00:00","dateModified":"2025-12-15T11:26:01+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/"},"wordCount":364,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/nl\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/","url":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/","name":"HOYER Group bereikt 50.000ste IBC-container - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/nl\/#website"},"datePublished":"2020-02-06T05:34:44+00:00","dateModified":"2025-12-15T11:26:01+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/nl\/2020\/02\/06\/hoyer-group-bereikt-50-000ste-ibc-container\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/nl\/"},{"@type":"ListItem","position":2,"name":"HOYER Group bereikt 50.000ste IBC-container"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/nl\/#website","url":"https:\/\/transportjournal.com\/nl\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/nl\/#organization","name":"Logismedia Groep AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/transportjournal.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Groep AG"},"image":{"@id":"https:\/\/transportjournal.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/posts\/17088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/comments?post=17088"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/posts\/17088\/revisions"}],"predecessor-version":[{"id":30573,"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/posts\/17088\/revisions\/30573"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/media?parent=17088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/categories?post=17088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/nl\/wp-json\/wp\/v2\/tags?post=17088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}