{"id":98316,"date":"2026-07-15T07:57:06","date_gmt":"2026-07-15T07:57:06","guid":{"rendered":"https:\/\/transportjournal.com\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/"},"modified":"2026-07-15T07:57:06","modified_gmt":"2026-07-15T07:57:06","slug":"turkish-cargo-espande-il-centro-merci-di-istanbul","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/","title":{"rendered":"Turkish Cargo espande il centro merci di Istanbul"},"content":{"rendered":"<p>Turkish Cargo ha annunciato un passo significativo per l&#8217;espansione del suo centro merci SMARTIST presso l&#8217;aeroporto di Istanbul. Con questo investimento, la capacit\u00e0 annuale di gestione passer\u00e0 da 2 milioni di tonnellate a 4,5 milioni di tonnellate, pi\u00f9 che raddoppiando. L&#8217;obiettivo \u00e8 soddisfare la crescente domanda globale e garantire al contempo un&#8217;elaborazione rapida e di alta qualit\u00e0 delle merci per i clienti. Questa espansione consolida la posizione di Istanbul come importante nodo internazionale per il trasporto aereo di merci.<\/p>\n<p>L\u00f6dige Industries, gi\u00e0 responsabile dell&#8217;equipaggiamento del terminal esistente (foto) con sistemi di gestione delle merci completamente automatizzati, \u00e8 stata nuovamente selezionata come partner tecnologico per questo progetto. La nuova fase, SMARTIST 2.0, si basa sui sistemi automatizzati installati nella prima fase nel 2021. Integra tecnologie moderne di automazione e digitalizzazione per ottimizzare ulteriormente l&#8217;efficienza operativa e migliorare la qualit\u00e0 del servizio per i clienti di Turkish Cargo.<\/p>\n<h3>Espansione dell&#8217;automazione e dell&#8217;efficienza<\/h3>\n<p>SMARTIST 2.0 rappresenta un ulteriore passo significativo nello sviluppo di una delle pi\u00f9 grandi strutture di carico al mondo, che copre una superficie totale di 370.000 m\u00b2. I sistemi innovativi sono progettati per la massima automazione e consentono una gestione fluida dello stoccaggio e del prelievo di Unit Load Devices (ULD) e pallet interni. Questo porta a tempi di elaborazione notevolmente pi\u00f9 rapidi nella gestione di processi logistici complessi.<\/p>\n<p>Murat Yal\u00e7\u0131n Kirca, Vice President per le Operazioni Cargo (Globale) di Turkish Cargo, sottolinea:<\/p>\n<blockquote>\n<p>\u201eCon SMARTIST 2.0, il nostro impegno va ben oltre la semplice espansione della capacit\u00e0. Rafforziamo il nostro ruolo nel trasporto aereo di merci globale attraverso un&#8217;infrastruttura intelligente. La prossima generazione della struttura di carico ci consente di gestire volumi crescenti senza interrompere le operazioni e garantisce una qualit\u00e0 del servizio continua per i nostri clienti in tutto il mondo.\u201d<\/p>\n<\/blockquote>\n<p>Bj\u00f6rn Ussat, Director Airport Logistic Solutions di L\u00f6dige Industries, esprime anch&#8217;egli un parere positivo:<\/p>\n<blockquote>\n<p>\u201eCon questo progetto di punta, Turkish Cargo rafforza le sue capacit\u00e0 di carico in uno degli aeroporti pi\u00f9 dinamici del mondo. Siamo orgogliosi che abbiano nuovamente fatto affidamento sulla nostra esperienza. Questo progetto sottolinea il nostro impegno a supportare la crescita di Turkish Cargo, garantendo al contempo i pi\u00f9 alti standard in termini di automazione ed eccellenza operativa.\u201d<\/p>\n<\/blockquote>\n<h3>Dettagli tecnici della nuova struttura<\/h3>\n<p>Il cuore del nuovo terminal \u00e8 un magazzino a scaffale alto di sei piani con 1.562 posizioni ULD. La struttura comprende nove veicoli di trasferimento elevatori da 15 piedi e dieci veicoli di trasferimento da 15 piedi. Inoltre, sono progettate 23 postazioni di lavoro elevatrici da 10 piedi e due postazioni di lavoro elevatrici da 20 piedi per una gestione ergonomica ed efficiente degli ULD. La soluzione \u00e8 completata da 22 piani anti-inclinazione, 76 piani angolari, due dock per camion da 20 piedi e quasi 1.000 piani motorizzati. Questi elementi perfettamente coordinati creano un sistema di flusso di materiali altamente flessibile e completamente integrato.<\/p>\n<p>Per supportare il trasporto rapido e stabile degli ULD, il sistema include anche un magazzino interno per pallet con 28 dispositivi di movimentazione, due hoist, 882 nastri trasportatori automatizzati per lo stoccaggio e il prelievo, nonch\u00e9 18.216 posti di stoccaggio per pallet interni con dimensioni di 1,2 m x 1,2 m. Questi componenti garantiscono un funzionamento continuo e potente in tutta la struttura, assicurando un&#8217;elaborazione tempestiva e affidabile di tutti i tipi di merci.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.lodige.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.lodige.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.turkishcargo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.turkishcargo.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Turkish Cargo espande il suo centro merci SMARTIST presso l&#8217;aeroporto di Istanbul, aumentando la capacit\u00e0 da 2,0 milioni a 4,5 milioni di tonnellate all&#8217;anno.<\/p>\n","protected":false},"author":12,"featured_media":98312,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1638,1633,1630],"tags":[4848,7129,30164,2794,72493,14965,14966,72494,14967,72495,72496,41386,72497,72498,64876,13634,13635,14974,14975,72499,1957,48744,72500,2810,2811,72501,72502,3234,30314,2952,2123,4871,2817,30317,72503,72504,2960,2961,2133,1831,7149,2176,72505,13587,72506,72507,2148,66470,2106,72508,72509,72510,13662,72511,72512],"class_list":["post-98316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-intralogistica","category-trasporto-aereo","tag-air-freight-hub","tag-airport-logistics","tag-amelioration-de-lefficacite-dans-la-logistique","tag-augmenter-la-capacite-de-fret","tag-automated-warehousing","tag-automation-in-logistics","tag-automatisation-dans-la-logistique","tag-automatisierte-lagerhaltung","tag-automatisierung-in-der-logistik","tag-cargo-center-istanbul","tag-cargo-facilities-worldwide","tag-cargo-handling-systems","tag-centre-de-fret-istanbul","tag-details-techniques-du-centre-de-fret","tag-deutsch-turkish-cargo","tag-digital-technologies-in-logistics","tag-digitale-technologien-in-der-logistik","tag-efficiency-improvement-in-logistics","tag-effizienzsteigerung-in-der-logistik","tag-entreposage-automatise","tag-flughafenlogistik","tag-frachtabwicklungssysteme","tag-frachtanlagen-weltweit","tag-frachtkapazitaet-erhoehen","tag-frachtlogistik","tag-frachtverkehr-optimieren","tag-frachtzentrum-istanbul","tag-freight-logistics","tag-freight-transport-infrastructure","tag-fret-aerien-international","tag-gestion-de-la-chaine-dapprovisionnement","tag-hub-de-fret-aerien","tag-increase-cargo-capacity","tag-infrastructure-de-transport-de-fret","tag-infrastruktur-fuer-frachtverkehr","tag-installations-de-fret-dans-le-monde","tag-international-air-freight","tag-internationale-luftfracht","tag-logistics-service-providers","tag-logistikdienstleister","tag-logistique-aeroportuaire","tag-logistique-de-fret","tag-luftfrachtknoten","tag-manipulation-des-uld","tag-optimiser-le-trafic-de-fret","tag-optimize-freight-traffic","tag-prestataires-de-services-logistiques","tag-smartist-2-0","tag-supply-chain-management","tag-systemes-de-traitement-de-fret","tag-technical-details-cargo-center","tag-technische-details-frachtzentrum","tag-technologies-numeriques-dans-la-logistique","tag-uld-handhabung-english-turkish-cargo","tag-uld-handling-francais-turkish-cargo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Turkish Cargo espande il centro merci di Istanbul - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turkish Cargo espande il centro merci di Istanbul - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Turkish Cargo espande il suo centro merci SMARTIST presso l&#039;aeroporto di Istanbul, aumentando la capacit\u00e0 da 2,0 milioni a 4,5 milioni di tonnellate all&#039;anno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T07:57:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/07\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"Turkish Cargo espande il centro merci di Istanbul\",\"datePublished\":\"2026-07-15T07:57:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/\"},\"wordCount\":553,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"keywords\":[\"air freight hub\",\"airport logistics\",\"am\u00e9lioration de l'efficacit\u00e9 dans la logistique\",\"augmenter la capacit\u00e9 de fret\",\"automated warehousing\",\"automation in logistics\",\"automatisation dans la logistique\",\"automatisierte Lagerhaltung\",\"Automatisierung in der Logistik\",\"cargo center Istanbul\",\"cargo facilities worldwide\",\"cargo handling systems\",\"centre de fret Istanbul\",\"d\u00e9tails techniques du centre de fret\",\"Deutsch Turkish Cargo\",\"digital technologies in logistics\",\"digitale Technologien in der Logistik\",\"efficiency improvement in logistics\",\"Effizienzsteigerung in der Logistik\",\"entreposage automatis\u00e9\",\"Flughafenlogistik\",\"Frachtabwicklungssysteme\",\"Frachtanlagen weltweit\",\"Frachtkapazit\u00e4t erh\u00f6hen\",\"Frachtlogistik\",\"Frachtverkehr optimieren\",\"Frachtzentrum Istanbul\",\"freight logistics\",\"freight transport infrastructure\",\"fret a\u00e9rien international\",\"gestion de la cha\u00eene d'approvisionnement\",\"hub de fret a\u00e9rien\",\"increase cargo capacity\",\"infrastructure de transport de fret\",\"Infrastruktur f\u00fcr Frachtverkehr\",\"installations de fret dans le monde\",\"international air freight\",\"internationale Luftfracht\",\"logistics service providers\",\"Logistikdienstleister\",\"logistique a\u00e9roportuaire\",\"logistique de fret\",\"Luftfrachtknoten\",\"manipulation des ULD\",\"optimiser le trafic de fret\",\"optimize freight traffic\",\"prestataires de services logistiques\",\"SMARTIST 2.0\",\"Supply Chain Management\",\"syst\u00e8mes de traitement de fret\",\"technical details cargo center\",\"technische Details Frachtzentrum\",\"technologies num\u00e9riques dans la logistique\",\"ULD Handhabung English Turkish Cargo\",\"ULD handling Fran\u00e7ais Turkish Cargo\"],\"articleSection\":[\"Europa\",\"Intralogistica\",\"Trasporto aereo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/\",\"name\":\"Turkish Cargo espande il centro merci di Istanbul - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"datePublished\":\"2026-07-15T07:57:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"width\":2560,\"height\":1441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2026\\\/07\\\/15\\\/turkish-cargo-espande-il-centro-merci-di-istanbul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turkish Cargo espande il centro merci di Istanbul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turkish Cargo espande il centro merci di Istanbul - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/","og_locale":"it_IT","og_type":"article","og_title":"Turkish Cargo espande il centro merci di Istanbul - ITJ | International Transport Journal","og_description":"Turkish Cargo espande il suo centro merci SMARTIST presso l'aeroporto di Istanbul, aumentando la capacit\u00e0 da 2,0 milioni a 4,5 milioni di tonnellate all'anno.","og_url":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2026-07-15T07:57:06+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/07\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg","type":"image\/jpeg"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andreas Haug","Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/transportjournal.com\/it\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"Turkish Cargo espande il centro merci di Istanbul","datePublished":"2026-07-15T07:57:06+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/"},"wordCount":553,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/07\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg","keywords":["air freight hub","airport logistics","am\u00e9lioration de l'efficacit\u00e9 dans la logistique","augmenter la capacit\u00e9 de fret","automated warehousing","automation in logistics","automatisation dans la logistique","automatisierte Lagerhaltung","Automatisierung in der Logistik","cargo center Istanbul","cargo facilities worldwide","cargo handling systems","centre de fret Istanbul","d\u00e9tails techniques du centre de fret","Deutsch Turkish Cargo","digital technologies in logistics","digitale Technologien in der Logistik","efficiency improvement in logistics","Effizienzsteigerung in der Logistik","entreposage automatis\u00e9","Flughafenlogistik","Frachtabwicklungssysteme","Frachtanlagen weltweit","Frachtkapazit\u00e4t erh\u00f6hen","Frachtlogistik","Frachtverkehr optimieren","Frachtzentrum Istanbul","freight logistics","freight transport infrastructure","fret a\u00e9rien international","gestion de la cha\u00eene d'approvisionnement","hub de fret a\u00e9rien","increase cargo capacity","infrastructure de transport de fret","Infrastruktur f\u00fcr Frachtverkehr","installations de fret dans le monde","international air freight","internationale Luftfracht","logistics service providers","Logistikdienstleister","logistique a\u00e9roportuaire","logistique de fret","Luftfrachtknoten","manipulation des ULD","optimiser le trafic de fret","optimize freight traffic","prestataires de services logistiques","SMARTIST 2.0","Supply Chain Management","syst\u00e8mes de traitement de fret","technical details cargo center","technische Details Frachtzentrum","technologies num\u00e9riques dans la logistique","ULD Handhabung English Turkish Cargo","ULD handling Fran\u00e7ais Turkish Cargo"],"articleSection":["Europa","Intralogistica","Trasporto aereo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/","url":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/","name":"Turkish Cargo espande il centro merci di Istanbul - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/07\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg","datePublished":"2026-07-15T07:57:06+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/07\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/07\/smartist_terminal-1-scaled-aspect-ratio-1400-788-scaled-1.jpg","width":2560,"height":1441},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/it\/2026\/07\/15\/turkish-cargo-espande-il-centro-merci-di-istanbul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/it\/"},{"@type":"ListItem","position":2,"name":"Turkish Cargo espande il centro merci di Istanbul"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/it\/#website","url":"https:\/\/transportjournal.com\/it\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/it\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/it\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/transportjournal.com\/it\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/98316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/comments?post=98316"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/98316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media\/98312"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media?parent=98316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/categories?post=98316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/tags?post=98316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}