{"id":65720,"date":"2024-07-07T10:33:09","date_gmt":"2024-07-07T08:33:09","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/"},"modified":"2024-07-07T10:33:09","modified_gmt":"2024-07-07T08:33:09","slug":"la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/","title":{"rendered":"La Deutsche Post accoglie in linea di principio la nuova legge postale"},"content":{"rendered":"<h5>La Deutsche Post accoglie la nuova legge postale, ma si tutela gi\u00e0 per giustificare eventuali aumenti dei prezzi. In particolare, la Deutsche Post critica anche i nuovi strumenti previsti per stimolare artificialmente la concorrenza nel mercato delle lettere in contrazione, come ad esempio l&#8217;obbligo di coerenza delle tariffe, la cattura dei maggiori ricavi in caso di violazioni delle complesse normative tariffarie o l&#8217;accesso alla rete per le spedizioni di merci e la posta della stampa. Anche se il mercato delle lettere \u00e8 in contrazione, la concorrenza non pu\u00f2 fare male.<\/h5>\n<p>(Bonn\/Berlino) La Deutsche Post accoglie con favore il fatto che oggi il Bundesrat ha approvato la &#8220;Legge per la modernizzazione del diritto postale&#8221; e ora le condizioni quadro per la futura fornitura postale sono definite. Dopo che in precedenza il Bundestag tedesco aveva gi\u00e0 dato il suo consenso, la legge entrer\u00e0 in vigore probabilmente gi\u00e0 a luglio. Essa abroga sia la legge postale che il regolamento sui servizi postali universali del 1998 e pone la fornitura capillare di lettere e pacchi in Germania (noto anche come servizio postale universale) su una nuova base giuridica. La tanto attesa modernizzazione della legge consente alla Deutsche Post di continuare a fornire il servizio postale universale anche in tempi di trasformazione strutturale - un netto calo delle lettere e un aumento dei pacchi.<\/p>\n<aside class=\"c-text-quote-highlight component-margin component-full has-rte l-grid l-grid--middle-s-l animation--slide-up animation--fade-in animation--duration-900 animation--offsety-200\">\n<div class=\"c-text-quote-highlight--wrapper component-small  has-image\">\n<blockquote class=\"c-text-quote-highlight--quote quotes-enabled  \">\n<div class=\"has-rte\">\n<p class=\"has-rte\">Accogliamo con favore il fatto che i nostri dipendenti, clienti e investitori abbiano finalmente chiarezza sulle future condizioni quadro della fornitura postale. La legge ci consente di continuare a fornire il servizio postale universale in Germania. Tuttavia, presenta anche evidenti debolezze: il percorso speciale tedesco per la promozione della concorrenza nel mercato delle lettere in contrazione porter\u00e0 a un aumento dei costi dei servizi universali. Inoltre, mette a rischio la qualit\u00e0, poich\u00e9 i concorrenti spesso immettono le spedizioni nella rete della Deutsche Post senza preavviso, rendendo cos\u00ec la consegna pi\u00f9 difficile da pianificare e quindi pi\u00f9 complicata e costosa. Tobias Meyer, CEO del gruppo DHL<\/p>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/aside>\n<div class=\"component-margin c-text-generic has-rte component-small \">\n<div class=\"has-rte\">\n<p>In particolare, la Deutsche Post critica anche i nuovi strumenti previsti per stimolare artificialmente la concorrenza nel mercato delle lettere in contrazione, come ad esempio l&#8217;obbligo di coerenza delle tariffe, la cattura dei maggiori ricavi in caso di violazioni delle complesse normative tariffarie o l&#8217;accesso alla rete per le spedizioni di merci e la posta della stampa. La Germania continua a seguire un percorso speciale nella promozione della concorrenza nel settore delle lettere, che in altri Stati membri dell&#8217;UE \u00e8 gi\u00e0 fallito. Misure comparabili hanno portato in altri paesi a prezzi pi\u00f9 elevati e a una qualit\u00e0 inferiore. \u00c8 altrettanto incomprensibile l&#8217;enorme aumento della burocrazia che la nuova legge postale comporta, ad esempio attraverso l&#8217;introduzione di nuovi obblighi di reporting e l&#8217;espansione della regolamentazione nel settore dei pacchi.<\/p>\n<h5><b>Modifiche ai prodotti postali <\/b><\/h5>\n<p>La nuova legge postale prevede che le lettere possano impiegare pi\u00f9 tempo per arrivare a destinazione a partire dal 2025. Il 95% delle spedizioni di lettere dovr\u00e0 arrivare entro tre giorni dalla consegna, invece dei due giorni previsti finora. Attualmente si prevede di offrire ai clienti delle lettere la possibilit\u00e0 di scegliere i tempi di consegna a partire dal 2025.<\/p>\n<h5><b>Modifiche nel settore dei pacchi <\/b><\/h5>\n<p>Secondo la nuova legge postale, i pacchi che superano un peso di 10 kg e quelli che superano un peso di 20 kg devono essere contrassegnati con un avviso ben visibile e facilmente comprensibile riguardo al peso elevato.<\/p>\n<h5><b>Impatto sulla rete di filiali <\/b><\/h5>\n<p>La nuova legge postale mantiene l&#8217;obbligo che in tutta la Germania devono continuare a esserci 12.000 filiali postali. Prevede inoltre la possibilit\u00e0 di stazioni automatizzate al posto delle filiali del servizio universale. La Deutsche Post accoglie con favore questa modernizzazione, poich\u00e9 i distributori automatici sono molto popolari - anche per la loro accessibilit\u00e0 quasi continua - e in alcune localit\u00e0 diventa sempre pi\u00f9 difficile trovare locali commerciali o rivenditori adatti per gestire le filiali. La Deutsche Post continuer\u00e0 a garantire che ogni comune sia fornito in modo adeguato e conforme ai servizi postali.<\/p>\n<p>Foto: \u00a9 Deutsche Post DHL<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Deutsche Post accoglie la nuova legge postale, ma si tutela gi\u00e0 per giustificare eventuali aumenti dei prezzi. In particolare, la Deutsche Post critica anche i<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-65720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Deutsche Post accoglie in linea di principio la nuova legge postale - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Deutsche Post accoglie in linea di principio la nuova legge postale - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"La Deutsche Post accoglie la nuova legge postale, ma si tutela gi\u00e0 per giustificare eventuali aumenti dei prezzi. In particolare, la Deutsche Post critica anche i [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-07T08:33:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Deutsche Post accoglie in linea di principio la nuova legge postale\",\"datePublished\":\"2024-07-07T08:33:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/\"},\"wordCount\":673,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DHL_7.7.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/\",\"name\":\"La Deutsche Post accoglie in linea di principio la nuova legge postale - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DHL_7.7.24.jpg\",\"datePublished\":\"2024-07-07T08:33:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DHL_7.7.24.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DHL_7.7.24.jpg\",\"width\":1214,\"height\":782},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2024\\\/07\\\/07\\\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Deutsche Post accoglie in linea di principio la nuova legge postale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Deutsche Post accoglie in linea di principio la nuova legge postale - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/","og_locale":"it_IT","og_type":"article","og_title":"La Deutsche Post accoglie in linea di principio la nuova legge postale - ITJ | International Transport Journal","og_description":"La Deutsche Post accoglie la nuova legge postale, ma si tutela gi\u00e0 per giustificare eventuali aumenti dei prezzi. In particolare, la Deutsche Post critica anche i [\u2026]","og_url":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2024-07-07T08:33:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/"},"author":{"name":"","@id":""},"headline":"La Deutsche Post accoglie in linea di principio la nuova legge postale","datePublished":"2024-07-07T08:33:09+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/"},"wordCount":673,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DHL_7.7.24.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/","url":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/","name":"La Deutsche Post accoglie in linea di principio la nuova legge postale - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DHL_7.7.24.jpg","datePublished":"2024-07-07T08:33:09+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DHL_7.7.24.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DHL_7.7.24.jpg","width":1214,"height":782},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/it\/2024\/07\/07\/la-deutsche-post-accoglie-in-linea-di-principio-la-nuova-legge-postale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/it\/"},{"@type":"ListItem","position":2,"name":"La Deutsche Post accoglie in linea di principio la nuova legge postale"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/it\/#website","url":"https:\/\/transportjournal.com\/it\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/it\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/65720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/comments?post=65720"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/65720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media\/6336"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media?parent=65720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/categories?post=65720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/tags?post=65720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}