{"id":63383,"date":"2023-11-11T17:01:29","date_gmt":"2023-11-11T16:01:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/"},"modified":"2023-11-11T17:01:29","modified_gmt":"2023-11-11T16:01:29","slug":"il-primo-treno-del-progetto-log4nrw-e-partito","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/","title":{"rendered":"Il primo treno del progetto &#8220;LOG4NRW&#8221; \u00e8 partito"},"content":{"rendered":"<h5>Via dalla strada, su rotaia e nave: circa 27.000 viaggi di camion saranno resi superflui da un&#8217;alleanza potente di diversi porti e operatori ferroviari nella Renania Settentrionale-Vestfalia. Ora il primo treno container nell&#8217;ambito del progetto &#8220;LOG4NRW&#8221; \u00e8 partito. Anche il treno inaugurale era carico oltre il 90% al momento della partenza da Kreuztal. Dal terminal container di S\u00fcdwestfalen a Kreuztal, il treno \u00e8 partito per Dortmund e poi per Duisburg. Qui sono stati caricati su una nave fluviale e portati a Rotterdam. In futuro, due treni container circoleranno settimanalmente tra S\u00fcdwestfalen e la regione della Ruhr.<\/h5>\n<p> L&#8217;iniziativa \u00e8 sotto la patronanza di Oliver Krischer, Ministro per l&#8217;Ambiente, la Conservazione della Natura e i Trasporti della Renania Settentrionale-Vestfalia. &#8220;Sono felice che LOG4NRW sia partito cos\u00ec rapidamente e con successo. Il trasferimento del traffico dalla strada alla ferrovia \u00e8 un elemento importante della transizione dei trasporti. Soluzioni logistiche sostenibili beneficiano sia l&#8217;economia che la protezione del clima&#8221;, ha dichiarato Krischer.<\/p>\n<h5>L&#8217;obiettivo \u00e8 alleviare in modo tangibile la situazione del traffico nella regione della Ruhr e a S\u00fcdwestfalen. Il concetto previsto prevede il seguente collegamento: Voerde-Emmelsum (Terminal container Contargo) \u2013 Duisburg-Walsum logport VI (Terminal multimodale Duisburg) \u2013 Porto di Dortmund (CTD Terminal container Dortmund) \u2013 Siegerland (Terminal container S\u00fcdwestfalen a Kreuztal) e ritorno. Questo porter\u00e0 a un immediato sollievo delle autostrade 2, 4 e 45 e della gi\u00e0 tesa situazione del traffico a S\u00fcdwestfalen, in particolare nell&#8217;area di Sauerland. Inoltre, il sistema combinato ferrovia-nave fluviale consente per la prima volta trasporti tra i terminal di Duisburg, Voerde-Emmelsum, Dortmund e Kreuztal. Poich\u00e9 il porto di Emmelsum sul Reno inferiore non pu\u00f2 attualmente essere raggiunto in treno a causa di un ponte danneggiato, duisport utilizza i suoi taxi acquatici su questo collegamento.<\/h5>\n<h5>Prenotazioni per tutti i partner tramite l&#8217;agenzia duisport<\/h5>\n<p> La gestione delle prenotazioni per tutti i partner di cooperazione \u00e8 stata assunta dalla duisport agency GmbH come societ\u00e0 centrale di marketing e vendita del gruppo duisport. La trazione dei treni \u00e8 effettuata congiuntamente dalla sussidiaria di duisport, duisport rail GmbH, e dalla Dortmund Eisenbahn \u2013 da Emmelsum attraverso logport VI a Duisburg, il porto di Dortmund e il CTD fino a Kreuztal.<\/p>\n<h5>&#8220;Il fatto che possiamo partire gi\u00e0 due mesi dopo i primi colloqui con potenziali clienti dimostra: avevamo l&#8217;idea giusta al momento giusto. Non da ultimo, in vista dell&#8217;aumento delle tariffe autostradali a dicembre, la ferrovia si dimostra ancora una volta un&#8217;eccellente alternativa e un vero risolutore di problemi&#8221;, afferma il CEO di duisport Markus Bangen. &#8220;In particolare nella nostra Renania Settentrionale-Vestfalia, gravata dal traffico, con problemi infrastrutturali purtroppo in aumento, vediamo il futuro della logistica in un&#8217;intelligente integrazione dei mezzi di trasporto. La nostra cooperazione crea quindi resilienza attraverso il trasferimento attuato del traffico e ha un impatto immensamente sostenibile riducendo il carico di emissioni dei trasporti&#8221;, afferma il direttore generale di DeltaPort Andreas Stolte. &#8220;Il marchio &#8216;LOG4NRW&#8217; \u00e8 in movimento. Con il primo treno diventa chiaro che come forti partner sul mercato funzioniamo bene insieme e offriamo un&#8217;offerta logistica mirata e attraente. Stiamo plasmando insieme e attivamente con le aziende la transizione dei trasporti e offriamo a tutti gli ulteriori interessati un prodotto orientato al futuro&#8221;, afferma il membro del consiglio del porto di Dortmund Bettina Brennenstuhl.<\/h5>\n<h5>Interesse dell&#8217;industria caricatori \u00e8 incoraggiante<\/h5>\n<p> &#8220;L&#8217;interesse dell&#8217;industria caricatori per il nuovo prodotto ferroviario \u00e8 sorprendentemente grande nonostante le difficolt\u00e0 del mercato per il trasporto combinato in Europa. Le nostre aziende locali dipendono necessariamente dai trasporti di gruppi di vagoni, singoli vagoni e dal trasporto combinato, poich\u00e9 la maggior parte di esse non \u00e8 in grado di gestire il volume per treni completi. LOG4NRW \u00e8 quindi essenziale per la logistica della regione industriale pi\u00f9 forte della Renania Settentrionale-Vestfalia, S\u00fcdwestfalen&#8221;, afferma Christian Betchen, amministratore delegato della KSW Kreisbahn Siegen-Wittgenstein GmbH e della S\u00fcdwestfalen Container-Terminal GmbH.<br \/>Foto: \u00a9 LOG4NRW<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Via dalla strada, su rotaia e nave: circa 27.000 viaggi di camion saranno resi superflui da un&#8217;alleanza potente di diversi porti e operatori ferroviari nella Renania<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7299,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-63383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il primo treno del progetto &quot;LOG4NRW&quot; \u00e8 partito - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il primo treno del progetto &quot;LOG4NRW&quot; \u00e8 partito - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Via dalla strada, su rotaia e nave: circa 27.000 viaggi di camion saranno resi superflui da un&#8217;alleanza potente di diversi porti e operatori ferroviari nella Renania [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-11T16:01:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Il primo treno del progetto &#8220;LOG4NRW&#8221; \u00e8 partito\",\"datePublished\":\"2023-11-11T16:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/\"},\"wordCount\":646,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/duisport_11.11.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/\",\"name\":\"Il primo treno del progetto \\\"LOG4NRW\\\" \u00e8 partito - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/duisport_11.11.23.jpg\",\"datePublished\":\"2023-11-11T16:01:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/duisport_11.11.23.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/duisport_11.11.23.jpg\",\"width\":1463,\"height\":911},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/11\\\/11\\\/il-primo-treno-del-progetto-log4nrw-e-partito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il primo treno del progetto &#8220;LOG4NRW&#8221; \u00e8 partito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il primo treno del progetto \"LOG4NRW\" \u00e8 partito - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/","og_locale":"it_IT","og_type":"article","og_title":"Il primo treno del progetto \"LOG4NRW\" \u00e8 partito - ITJ | International Transport Journal","og_description":"Via dalla strada, su rotaia e nave: circa 27.000 viaggi di camion saranno resi superflui da un&#8217;alleanza potente di diversi porti e operatori ferroviari nella Renania [\u2026]","og_url":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2023-11-11T16:01:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/"},"author":{"name":"","@id":""},"headline":"Il primo treno del progetto &#8220;LOG4NRW&#8221; \u00e8 partito","datePublished":"2023-11-11T16:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/"},"wordCount":646,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/duisport_11.11.23.jpg","articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/","url":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/","name":"Il primo treno del progetto \"LOG4NRW\" \u00e8 partito - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/duisport_11.11.23.jpg","datePublished":"2023-11-11T16:01:29+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/duisport_11.11.23.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/duisport_11.11.23.jpg","width":1463,"height":911},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/it\/2023\/11\/11\/il-primo-treno-del-progetto-log4nrw-e-partito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il primo treno del progetto &#8220;LOG4NRW&#8221; \u00e8 partito"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/it\/#website","url":"https:\/\/transportjournal.com\/it\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/it\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/63383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/comments?post=63383"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/63383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media\/7299"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media?parent=63383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/categories?post=63383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/tags?post=63383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}