{"id":63014,"date":"2023-10-10T16:53:48","date_gmt":"2023-10-10T14:53:48","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/"},"modified":"2023-10-10T16:53:48","modified_gmt":"2023-10-10T14:53:48","slug":"il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/","title":{"rendered":"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz"},"content":{"rendered":"<h5><strong>Luned\u00ec 9 ottobre, il progetto mFUND DiSTILL ha celebrato il suo avvio ufficiale a Cottbus. Il team di progetto desidera rappresentare in modo trasparente l&#8217;infrastruttura logistica della Lausitz brandeburghese-sassone e renderla pubblicamente accessibile. Sviluppando servizi logistici attorno alla ferrovia, si pu\u00f2 rafforzare il settore logistico e dei trasporti regionale. Uno strumento di simulazione pianificato consente all&#8217;utente di rendere visibile e valutabile la capacit\u00e0 logistica.<\/strong><\/h5>\n<p>(Cottbus) Per decenni, l&#8217;economia e la cultura della regione mineraria della Lausitz sono state caratterizzate dall&#8217;industria del carbone. Ora si sta trasformando in una regione innovativa per l&#8217;energia, l&#8217;industria e il turismo. Grazie alla sua favorevole posizione geografica, la regione ha il potenziale per partecipare attivamente alla rete europea di creazione di valore sostenibile e per svolgere un ruolo significativo. Il progetto DiSTILL (Strumento di simulazione digitale per lo sviluppo della regione della Lausitz come hub logistico internazionale) \u00e8 stato avviato per supportare miratamente questo sviluppo.<\/p>\n<p>Il progetto consortile \u00e8 coordinato dal Dipartimento di Logistica della Technische Universit\u00e4t Berlin sotto la direzione del Prof. Dr.-Ing. Frank Straube.<\/p>\n<h5>Ulteriori partner di progetto<\/h5>\n<ul>\n<li>Camerale di commercio e industria (IHK) di Cottbus,<\/li>\n<li>IPG Gesellschaft per lo sviluppo infrastrutturale e di progetto mbh,<\/li>\n<li>Azienda di sviluppo software i-ways,<\/li>\n<li>Azienda di logistica Lion Group,<\/li>\n<li>Azienda di trasporti e spedizioni Schwarze Pumpe (TSS) mbH,<\/li>\n<li>Agenzia PR Medienb\u00fcro am Reichstag.<\/li>\n<\/ul>\n<p>&#8220;La logistica \u00e8 una funzione chiave nello sviluppo sostenibile di una regione. Siamo felici di poter partecipare a questo sviluppo nella Lausitz come istituzione di ricerca&#8221;, afferma il Prof. Dr.-Ing. Frank Straube, responsabile del Dipartimento di Logistica della TU Berlino, sottolineando l&#8217;importanza di DiSTILL all&#8217;avvio del progetto.<\/p>\n<p>Jens Krause, portavoce della rete di trasporti economici della Lausitz e general manager per la transizione strutturale\/infrastruttura e trasporti presso l&#8217;IHK Cottbus, afferma: &#8220;La Lausitz \u00e8 ancora un&#8217;area bianca sulle mappe logistiche internazionali, mentre la mobilit\u00e0 sostenibile qui viene attuata sempre di pi\u00f9. Pertanto, \u00e8 assolutamente necessario aumentare la visibilit\u00e0 per gli attori del settore logistico e dei trasporti e per i servizi nella regione. Siamo ansiosi di implementare con successo il progetto.&#8221;<\/p>\n<h5>Rendere la regione Lausitz pi\u00f9 conosciuta<\/h5>\n<p>Il team di progetto lavorer\u00e0 sui pacchetti di lavoro definiti in precedenza fino all&#8217;inizio del 2026. Come risultato, dovrebbe emergere un&#8217;analisi delle attuali e future esigenze logistiche della regione della Lausitz, nonch\u00e9 un database con progetti infrastrutturali logistici attuali e pianificati. Sulla base di questi risultati, verr\u00e0 sviluppato uno strumento di simulazione digitale che si baser\u00e0 su dati liberamente disponibili. Questo strumento pu\u00f2 supportare nella gestione efficiente delle esigenze logistiche, promuovere una rete regionale robusta, far avanzare le reti di creazione di valore sostenibile e supportare le aziende esistenti nell&#8217;ottimizzazione dei loro processi logistici. Inoltre, la regione della Lausitz dovrebbe essere resa pi\u00f9 conosciuta sia a livello regionale che nazionale e internazionale. Il progetto DiSTILL \u00e8 finanziato nell&#8217;ambito dell&#8217;iniziativa di innovazione mFUND con circa 2 milioni di euro dal Ministero federale per la digitalizzazione e i trasporti.<\/p>\n<h5><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-24383 size-full\" src=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DiStill_10.10.23_1.jpg\" alt=\"\" width=\"1818\" height=\"974\" \/>Su DiSTILL<\/strong><\/h5>\n<p>Il progetto DiSTILL si dedica al supporto della regione della Lausitz nel contesto dello sviluppo regionale. Si intende sfruttare i punti di forza e le opportunit\u00e0 della regione e affrontare le sue sfide, al fine di preparare la regione alle esigenze logistiche del futuro e farla diventare un attore chiave nelle reti di creazione di valore sostenibile in Europa. Per raggiungere questo obiettivo complessivo, vengono definiti obiettivi di progetto che devono essere raggiunti durante la durata del progetto. Inoltre, verr\u00e0 sviluppato un modello di simulazione digitale della rete logistica della Lausitz, per rendere misurabile la performance logistica della regione. Lo strumento supporta gli utenti nella pianificazione di misure infrastrutturali e organizzative all&#8217;interno della Lausitz e promette cos\u00ec migliori stime costi-benefici e quindi anche pianificabilit\u00e0 per i progetti corrispondenti.<\/p>\n<h4><strong><a href=\"https:\/\/www.distill-lausitz.de\/\" target=\"_blank\" rel=\"noopener\">Ulteriori informazioni<\/a><\/strong><\/h4>\n<p>Foto\/Grafica: \u00a9 DiSTILL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 9 ottobre, il progetto mFUND DiSTILL ha celebrato il suo avvio ufficiale a Cottbus. Il team di progetto desidera rappresentare in modo trasparente l&#8217;infrastruttura logistica<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-63014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec 9 ottobre, il progetto mFUND DiSTILL ha celebrato il suo avvio ufficiale a Cottbus. Il team di progetto desidera rappresentare in modo trasparente l&#8217;infrastruttura logistica [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T14:53:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz\",\"datePublished\":\"2023-10-10T14:53:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/\"},\"wordCount\":638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DiStill_10.10.23_3.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/\",\"name\":\"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DiStill_10.10.23_3.jpg\",\"datePublished\":\"2023-10-10T14:53:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DiStill_10.10.23_3.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DiStill_10.10.23_3.jpg\",\"width\":1286,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/2023\\\/10\\\/10\\\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/","og_locale":"it_IT","og_type":"article","og_title":"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz - ITJ | International Transport Journal","og_description":"Luned\u00ec 9 ottobre, il progetto mFUND DiSTILL ha celebrato il suo avvio ufficiale a Cottbus. Il team di progetto desidera rappresentare in modo trasparente l&#8217;infrastruttura logistica [\u2026]","og_url":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2023-10-10T14:53:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/"},"author":{"name":"","@id":""},"headline":"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz","datePublished":"2023-10-10T14:53:48+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/"},"wordCount":638,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DiStill_10.10.23_3.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/","url":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/","name":"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DiStill_10.10.23_3.jpg","datePublished":"2023-10-10T14:53:48+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DiStill_10.10.23_3.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DiStill_10.10.23_3.jpg","width":1286,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/it\/2023\/10\/10\/il-progetto-distill-mira-a-rendere-trasparente-la-logistica-nella-lausitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il progetto DiSTILL mira a rendere trasparente la logistica nella Lausitz"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/it\/#website","url":"https:\/\/transportjournal.com\/it\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/it\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/transportjournal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/63014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/comments?post=63014"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/posts\/63014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media\/7453"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/media?parent=63014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/categories?post=63014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/it\/wp-json\/wp\/v2\/tags?post=63014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}