{"id":88597,"date":"2026-05-07T18:25:54","date_gmt":"2026-05-07T18:25:54","guid":{"rendered":"https:\/\/transportjournal.com\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/"},"modified":"2026-05-07T18:25:54","modified_gmt":"2026-05-07T18:25:54","slug":"db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/","title":{"rendered":"DB InfraGO fait le point sur l&rsquo;\u00e9tat du r\u00e9seau ferroviaire"},"content":{"rendered":"<p>L&#8217;\u00e9tat du r\u00e9seau ferroviaire allemand montre les premiers signes d&#8217;une stabilisation. Cela ressort du rapport d&#8217;\u00e9tat actuel de DB InfraGO pour l&#8217;ann\u00e9e 2025, qui attribue une note moyenne de 3,00 \u00e0 l&#8217;ensemble du r\u00e9seau ferroviaire. Cette note correspond \u00e0 celle de l&#8217;ann\u00e9e pr\u00e9c\u00e9dente et indique que la tendance \u00e0 la baisse de longue date pourrait \u00eatre interrompue. En particulier, les gares ont l\u00e9g\u00e8rement am\u00e9lior\u00e9 leur note, passant de 3,03 en 2024 \u00e0 2,96. Cela est en partie d\u00fb \u00e0 la r\u00e9novation compl\u00e8te de 124 gares l&#8217;ann\u00e9e derni\u00e8re.<\/p>\n<h3>Analyse de donn\u00e9es approfondie<\/h3>\n<p>Pour le rapport, plus de 380 000 installations de la voie ferr\u00e9e et des gares ont \u00e9t\u00e9 examin\u00e9es et \u00e9valu\u00e9es selon un syst\u00e8me de notation scolaire. Les \u00e9l\u00e9ments \u00e9valu\u00e9s comprennent des ponts, des tunnels, des ouvrages de sout\u00e8nement, des voies, des aiguillages, des passages \u00e0 niveau, des postes d&#8217;aiguillage, des lignes a\u00e9riennes ainsi que l&#8217;infrastructure des gares.<\/p>\n<p>Evelyn Palla, pr\u00e9sidente du conseil d&#8217;administration de la Deutsche Bahn, a comment\u00e9 les r\u00e9sultats : \u00ab Le creux de l&#8217;\u00e2ge non ma\u00eetris\u00e9 de notre infrastructure ferroviaire semble atteint. La note globale de notre r\u00e9seau ferroviaire reste au niveau de 2024 \u2013 un signe que le retournement de tendance n&#8217;est pas encore r\u00e9alis\u00e9. \u00bb Elle a soulign\u00e9 la n\u00e9cessit\u00e9 de mesures de modernisation suppl\u00e9mentaires et a appel\u00e9 \u00e0 un soutien financier ad\u00e9quat de la part des pouvoirs publics pour r\u00e9duire le retard d&#8217;investissement.<\/p>\n<p>En 2025, environ 1 900 kilom\u00e8tres de voies et 1 900 aiguillages ont \u00e9t\u00e9 renouvel\u00e9s. Des travaux ont eu lieu dans plus de 950 gares, y compris le renouvellement de 250 ascenseurs et escaliers m\u00e9caniques. De plus, 103 ponts d&#8217;une superficie totale d&#8217;environ 25 000 m\u00b2 ont \u00e9t\u00e9 r\u00e9nov\u00e9s, et 3 700 unit\u00e9s de commande de la technique de signalisation ont \u00e9t\u00e9 modernis\u00e9es. Un milliard d&#8217;euros suppl\u00e9mentaires de l&#8217;\u00c9tat f\u00e9d\u00e9ral a garanti des investissements dans des ponts complexes et des technologies modernes.<\/p>\n<h3>Investissements et leurs impacts<\/h3>\n<p>Dr. Philipp Nagl, pr\u00e9sident du conseil d&#8217;administration de DB InfraGO AG, a rapport\u00e9 des investissements d&#8217;environ 19,9 milliards d&#8217;euros pour des mesures d&#8217;entretien et de remplacement en 2025. Ces investissements ont contribu\u00e9 \u00e0 pr\u00e9venir une d\u00e9t\u00e9rioration suppl\u00e9mentaire de l&#8217;\u00e9tat des installations, bien que l&#8217;\u00e2ge moyen des installations continue d&#8217;augmenter. \u00ab Les volumes de construction accrus ont conduit en 2025, pour la premi\u00e8re fois depuis des ann\u00e9es, \u00e0 une diminution de la valeur des besoins de renouvellement pour les installations avec des notes d&#8217;\u00e9tat mauvaises, insuffisantes et restrictives \u00bb, a expliqu\u00e9 Nagl. Les besoins de renouvellement ont \u00e9t\u00e9 estim\u00e9s \u00e0 environ 110 milliards d&#8217;euros pour 2024, tandis qu&#8217;ils ont pu \u00eatre r\u00e9duits \u00e0 environ 106 milliards d&#8217;euros en 2025.<\/p>\n<p>La part des installations dans le r\u00e9seau ferroviaire qui doivent \u00eatre renouvel\u00e9es en raison de leur \u00e9tat est de 16,1 %. L&#8217;ann\u00e9e pr\u00e9c\u00e9dente, cette part \u00e9tait de 16,8 %, ce qui repr\u00e9sente une l\u00e9g\u00e8re am\u00e9lioration.<\/p>\n<p>La note d&#8217;\u00e9tat pour l&#8217;ing\u00e9nierie civile, qui comprend les ponts et les passages, s&#8217;est l\u00e9g\u00e8rement am\u00e9lior\u00e9e \u00e0 2,59. En revanche, la note d&#8217;\u00e9tat pour la superstructure, y compris les voies et les aiguillages, s&#8217;est d\u00e9t\u00e9rior\u00e9e de 0,06 \u00e0 3,02. Cela est d\u00fb \u00e0 9 600 kilom\u00e8tres de voies n\u00e9cessitant un renouvellement. Les aiguillages montrent \u00e9galement une l\u00e9g\u00e8re baisse dans l&#8217;\u00e9valuation, avec 15 800 sur un total de 64 000 aiguillages n\u00e9cessitant un renouvellement.<\/p>\n<p>Les postes d&#8217;aiguillage, not\u00e9s \u00e0 4,02, restent le secteur avec la pire note d&#8217;\u00e9tat. Un sur deux des quelque 4 000 postes d&#8217;aiguillage n\u00e9cessite un renouvellement. La note d&#8217;\u00e9tat des passages \u00e0 niveau s&#8217;est \u00e9galement l\u00e9g\u00e8rement d\u00e9t\u00e9rior\u00e9e, passant de 3,58 \u00e0 3,65.<\/p>\n<p>Dans les gares, une l\u00e9g\u00e8re am\u00e9lioration est observ\u00e9e, notamment au niveau des b\u00e2timents d&#8217;accueil et de la technique d&#8217;information et de t\u00e9l\u00e9communication. Cependant, un besoin de renouvellement consid\u00e9rable demeure.<\/p>\n<p>Dans l&#8217;\u00e9valuation de la voie ferr\u00e9e, les L\u00e4nder de l&#8217;est de l&#8217;Allemagne obtiennent de meilleurs r\u00e9sultats, ce qui est d\u00fb \u00e0 des investissements importants dans la modernisation du r\u00e9seau ferroviaire depuis la r\u00e9unification. Les notes varient de 2,65 en Thuringe \u00e0 2,89 dans le Brandebourg, tandis que le Hessen suit avec 2,95. La Rh\u00e9nanie-du-Nord-Westphalie a de nouveau la note globale la plus basse avec 3,26.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le rapport d&rsquo;\u00e9tat actuel de DB InfraGO montre une stabilisation du r\u00e9seau ferroviaire, avec une note moyenne de 3,00 et une l\u00e9g\u00e8re am\u00e9lioration des gares.<\/p>\n","protected":false},"author":7,"featured_media":88595,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1645],"tags":[],"class_list":["post-88597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DB InfraGO fait le point sur l&#8217;\u00e9tat du r\u00e9seau ferroviaire - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DB InfraGO fait le point sur l&#8217;\u00e9tat du r\u00e9seau ferroviaire - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Le rapport d&#039;\u00e9tat actuel de DB InfraGO montre une stabilisation du r\u00e9seau ferroviaire, avec une note moyenne de 3,00 et une l\u00e9g\u00e8re am\u00e9lioration des gares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T18:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/05\/Header-Foto-2-aspect-ratio-1400-788.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"853\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreas M\u00fcller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas M\u00fcller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/\"},\"author\":{\"name\":\"Andreas M\u00fcller\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/person\\\/7b1593b33567ba798d300c8a1b0b85b1\"},\"headline\":\"DB InfraGO fait le point sur l&rsquo;\u00e9tat du r\u00e9seau ferroviaire\",\"datePublished\":\"2026-05-07T18:25:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/\"},\"wordCount\":753,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Header-Foto-2-aspect-ratio-1400-788.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/\",\"name\":\"DB InfraGO fait le point sur l&#8217;\u00e9tat du r\u00e9seau ferroviaire - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Header-Foto-2-aspect-ratio-1400-788.jpg\",\"datePublished\":\"2026-05-07T18:25:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Header-Foto-2-aspect-ratio-1400-788.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Header-Foto-2-aspect-ratio-1400-788.jpg\",\"width\":853,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/05\\\/07\\\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DB InfraGO fait le point sur l&rsquo;\u00e9tat du r\u00e9seau ferroviaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. \",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/person\\\/7b1593b33567ba798d300c8a1b0b85b1\",\"name\":\"Andreas M\u00fcller\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/author\\\/logismedia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DB InfraGO fait le point sur l&#8217;\u00e9tat du r\u00e9seau ferroviaire - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/","og_locale":"fr_FR","og_type":"article","og_title":"DB InfraGO fait le point sur l&#8217;\u00e9tat du r\u00e9seau ferroviaire - ITJ | International Transport Journal","og_description":"Le rapport d'\u00e9tat actuel de DB InfraGO montre une stabilisation du r\u00e9seau ferroviaire, avec une note moyenne de 3,00 et une l\u00e9g\u00e8re am\u00e9lioration des gares.","og_url":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2026-05-07T18:25:54+00:00","og_image":[{"width":853,"height":480,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/05\/Header-Foto-2-aspect-ratio-1400-788.jpg","type":"image\/jpeg"}],"author":"Andreas M\u00fcller","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Andreas M\u00fcller","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/"},"author":{"name":"Andreas M\u00fcller","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/person\/7b1593b33567ba798d300c8a1b0b85b1"},"headline":"DB InfraGO fait le point sur l&rsquo;\u00e9tat du r\u00e9seau ferroviaire","datePublished":"2026-05-07T18:25:54+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/"},"wordCount":753,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/05\/Header-Foto-2-aspect-ratio-1400-788.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/","url":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/","name":"DB InfraGO fait le point sur l&#8217;\u00e9tat du r\u00e9seau ferroviaire - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/05\/Header-Foto-2-aspect-ratio-1400-788.jpg","datePublished":"2026-05-07T18:25:54+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/05\/Header-Foto-2-aspect-ratio-1400-788.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/05\/Header-Foto-2-aspect-ratio-1400-788.jpg","width":853,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/fr\/2026\/05\/07\/db-infrago-fait-le-point-sur-letat-du-reseau-ferroviaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"DB InfraGO fait le point sur l&rsquo;\u00e9tat du r\u00e9seau ferroviaire"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/fr\/#website","url":"https:\/\/transportjournal.com\/fr\/","name":"ITJ | International Transport Journal","description":"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. ","publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/person\/7b1593b33567ba798d300c8a1b0b85b1","name":"Andreas M\u00fcller","url":"https:\/\/transportjournal.com\/fr\/author\/logismedia\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/88597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/comments?post=88597"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/88597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/media\/88595"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/media?parent=88597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/categories?post=88597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/tags?post=88597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}