{"id":76049,"date":"2026-02-05T10:25:58","date_gmt":"2026-02-05T10:25:58","guid":{"rendered":"https:\/\/transportjournal.com\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/"},"modified":"2026-02-05T10:25:58","modified_gmt":"2026-02-05T10:25:58","slug":"le-chiffre-daffaires-augmente-a-barcelone","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/","title":{"rendered":"Le chiffre d&rsquo;affaires augmente \u00e0 Barcelone"},"content":{"rendered":"<p>Le port de Barcelone a cl\u00f4tur\u00e9 l&#8217;ann\u00e9e 2025 avec un chiffre d&#8217;affaires de 206 millions d&#8217;euros, ce qui repr\u00e9sente une augmentation de 3 % par rapport \u00e0 l&#8217;ann\u00e9e pr\u00e9c\u00e9dente. C&#8217;est la deuxi\u00e8me ann\u00e9e cons\u00e9cutive o\u00f9 le port enregistre un chiffre d&#8217;affaires sup\u00e9rieur \u00e0 200 millions d&#8217;euros. Les principales sources de revenus sont les redevances de concession, qui s&#8217;\u00e9l\u00e8vent \u00e0 96 millions d&#8217;euros et constituent la part la plus stable, ainsi que les redevances d&#8217;utilisation de 97 millions d&#8217;euros, qui se rapportent au trafic et aux activit\u00e9s portuaires.<\/p>\n<h3>Investissements et projets<\/h3>\n<p>Malgr\u00e9 la croissance du chiffre d&#8217;affaires, le b\u00e9n\u00e9fice d&#8217;exploitation a diminu\u00e9 de 6 % en 2025. Cette baisse est attribu\u00e9e par le port aux impacts financiers exceptionnels des investissements dans un nouveau terminal \u00e0 caf\u00e9. Sans ce fardeau, le b\u00e9n\u00e9fice op\u00e9rationnel aurait probablement atteint 57 millions d&#8217;euros, ce qui aurait repr\u00e9sent\u00e9 une augmentation de 14 % par rapport \u00e0 l&#8217;ann\u00e9e pr\u00e9c\u00e9dente. De plus, les segments des conteneurs d&#8217;importation et du trafic de liquides en vrac ont enregistr\u00e9 des valeurs record en 2025.<\/p>\n<p><a href=\"https:\/\/www.portdebarcelona.cat\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.portdebarcelona.cat<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le port de Barcelone a r\u00e9alis\u00e9 en 2025 un chiffre d&rsquo;affaires de 206 millions d&rsquo;euros, mais enregistre une baisse des b\u00e9n\u00e9fices par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente en raison d&rsquo;un nouveau terminal \u00e0 caf\u00e9.<\/p>\n","protected":false},"author":10,"featured_media":76047,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1587,1583],"tags":[13432,13433,13434,13435,13436,13437,13438,13439,5586,10388,4800,4801,4047,5010,13440,13441,13442,2909,13443,13444,13445,2125,4054,4815,13446,13447,13448,13449,13450,2133,1831,5016,5017,4061,13451,13452,13453,2925,13454,13455,4065,13456,2929,13457,2148,13458,13459,5611,13460,13461,4078,13462,13463,2155,13464,1837,5621,13465],"class_list":["post-76049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leurope","category-transport-maritime-et-ports","tag-activites-portuaires","tag-benefice-dexploitation","tag-betriebsgewinn","tag-bulk-liquid-traffic","tag-bulk-liquid-verkehr","tag-coffee-terminal","tag-concession-fees","tag-conteneurs-import","tag-croissance-des-revenus","tag-deutsch-hafen-barcelona","tag-digitalisierung-hafen","tag-digitalization-port","tag-durabilite-logistique","tag-economie-maritime","tag-fachkraeftemangel-hafen-english-barcelona-port","tag-frais-dutilisation","tag-hafenaktivitaeten","tag-hafenbetrieb","tag-hafenprojekte","tag-import-containers","tag-importcontainer","tag-industrie-du-transport","tag-infrastructure-portuaire","tag-infrastruktur-hafen","tag-investissements-portuaires","tag-investitionen-hafen","tag-kaffeeterminal","tag-konzessionsgebuehren","tag-labor-shortage-port-francais-port-de-barcelone","tag-logistics-service-providers","tag-logistikdienstleister","tag-maritime-economy","tag-maritime-wirtschaft","tag-nachhaltigkeit-logistik","tag-numerisation-portuaire","tag-nutzungsgebuehren","tag-operating-profit","tag-operations-portuaires","tag-penurie-de-main-doeuvre-portuaire","tag-port-activities","tag-port-infrastructure","tag-port-investments","tag-port-operations","tag-port-projects","tag-prestataires-de-services-logistiques","tag-projets-portuaires","tag-redevances-de-concession","tag-revenue-growth","tag-schifffahrt-barcelona","tag-shipping-barcelona","tag-sustainability-logistics","tag-terminal-a-cafe","tag-trafic-de-liquides-en-vrac","tag-transport-industry","tag-transport-maritime-barcelone","tag-transportwirtschaft","tag-umsatzsteigerung","tag-usage-fees"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le chiffre d&#8217;affaires augmente \u00e0 Barcelone - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le chiffre d&#8217;affaires augmente \u00e0 Barcelone - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Le port de Barcelone a r\u00e9alis\u00e9 en 2025 un chiffre d&#039;affaires de 206 millions d&#039;euros, mais enregistre une baisse des b\u00e9n\u00e9fices par rapport \u00e0 l&#039;ann\u00e9e pr\u00e9c\u00e9dente en raison d&#039;un nouveau terminal \u00e0 caf\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T10:25:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeremy Soland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Soland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/\"},\"author\":{\"name\":\"Jeremy Soland\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\"},\"headline\":\"Le chiffre d&rsquo;affaires augmente \u00e0 Barcelone\",\"datePublished\":\"2026-02-05T10:25:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/\"},\"wordCount\":200,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"keywords\":[\"activit\u00e9s portuaires\",\"b\u00e9n\u00e9fice d'exploitation\",\"Betriebsgewinn\",\"bulk liquid traffic\",\"Bulk-Liquid-Verkehr\",\"coffee terminal\",\"concession fees\",\"conteneurs import\",\"croissance des revenus\",\"Deutsch Hafen Barcelona\",\"Digitalisierung Hafen\",\"digitalization port\",\"durabilit\u00e9 logistique\",\"\u00e9conomie maritime\",\"Fachkr\u00e4ftemangel Hafen English Barcelona port\",\"frais d'utilisation\",\"Hafenaktivit\u00e4ten\",\"Hafenbetrieb\",\"Hafenprojekte\",\"import containers\",\"Importcontainer\",\"industrie du transport\",\"infrastructure portuaire\",\"Infrastruktur Hafen\",\"investissements portuaires\",\"Investitionen Hafen\",\"Kaffeeterminal\",\"Konzessionsgeb\u00fchren\",\"labor shortage port Fran\u00e7ais Port de Barcelone\",\"logistics service providers\",\"Logistikdienstleister\",\"maritime economy\",\"maritime Wirtschaft\",\"Nachhaltigkeit Logistik\",\"num\u00e9risation portuaire\",\"Nutzungsgeb\u00fchren\",\"operating profit\",\"op\u00e9rations portuaires\",\"p\u00e9nurie de main-d'\u0153uvre portuaire\",\"port activities\",\"port infrastructure\",\"port investments\",\"port operations\",\"port projects\",\"prestataires de services logistiques\",\"projets portuaires\",\"redevances de concession\",\"revenue growth\",\"Schifffahrt Barcelona\",\"shipping Barcelona\",\"sustainability logistics\",\"terminal \u00e0 caf\u00e9\",\"trafic de liquides en vrac\",\"transport industry\",\"transport maritime Barcelone\",\"Transportwirtschaft\",\"Umsatzsteigerung\",\"usage fees\"],\"articleSection\":[\"L'Europe\",\"Transport maritime et ports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/\",\"name\":\"Le chiffre d&#8217;affaires augmente \u00e0 Barcelone - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"datePublished\":\"2026-02-05T10:25:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"width\":2560,\"height\":1441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2026\\\/02\\\/05\\\/le-chiffre-daffaires-augmente-a-barcelone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le chiffre d&rsquo;affaires augmente \u00e0 Barcelone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. \",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\",\"name\":\"Jeremy Soland\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/author\\\/jeremy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le chiffre d&#8217;affaires augmente \u00e0 Barcelone - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/","og_locale":"fr_FR","og_type":"article","og_title":"Le chiffre d&#8217;affaires augmente \u00e0 Barcelone - ITJ | International Transport Journal","og_description":"Le port de Barcelone a r\u00e9alis\u00e9 en 2025 un chiffre d'affaires de 206 millions d'euros, mais enregistre une baisse des b\u00e9n\u00e9fices par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente en raison d'un nouveau terminal \u00e0 caf\u00e9.","og_url":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2026-02-05T10:25:58+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg","type":"image\/jpeg"}],"author":"Jeremy Soland","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jeremy Soland","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/"},"author":{"name":"Jeremy Soland","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa"},"headline":"Le chiffre d&rsquo;affaires augmente \u00e0 Barcelone","datePublished":"2026-02-05T10:25:58+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/"},"wordCount":200,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg","keywords":["activit\u00e9s portuaires","b\u00e9n\u00e9fice d'exploitation","Betriebsgewinn","bulk liquid traffic","Bulk-Liquid-Verkehr","coffee terminal","concession fees","conteneurs import","croissance des revenus","Deutsch Hafen Barcelona","Digitalisierung Hafen","digitalization port","durabilit\u00e9 logistique","\u00e9conomie maritime","Fachkr\u00e4ftemangel Hafen English Barcelona port","frais d'utilisation","Hafenaktivit\u00e4ten","Hafenbetrieb","Hafenprojekte","import containers","Importcontainer","industrie du transport","infrastructure portuaire","Infrastruktur Hafen","investissements portuaires","Investitionen Hafen","Kaffeeterminal","Konzessionsgeb\u00fchren","labor shortage port Fran\u00e7ais Port de Barcelone","logistics service providers","Logistikdienstleister","maritime economy","maritime Wirtschaft","Nachhaltigkeit Logistik","num\u00e9risation portuaire","Nutzungsgeb\u00fchren","operating profit","op\u00e9rations portuaires","p\u00e9nurie de main-d'\u0153uvre portuaire","port activities","port infrastructure","port investments","port operations","port projects","prestataires de services logistiques","projets portuaires","redevances de concession","revenue growth","Schifffahrt Barcelona","shipping Barcelona","sustainability logistics","terminal \u00e0 caf\u00e9","trafic de liquides en vrac","transport industry","transport maritime Barcelone","Transportwirtschaft","Umsatzsteigerung","usage fees"],"articleSection":["L'Europe","Transport maritime et ports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/","url":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/","name":"Le chiffre d&#8217;affaires augmente \u00e0 Barcelone - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg","datePublished":"2026-02-05T10:25:58+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/02\/2bbfd6eb-ad01-44b7-8c3e-4e7a7216ee31-scaled-aspect-ratio-1400-788-scaled-1.jpg","width":2560,"height":1441},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/fr\/2026\/02\/05\/le-chiffre-daffaires-augmente-a-barcelone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le chiffre d&rsquo;affaires augmente \u00e0 Barcelone"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/fr\/#website","url":"https:\/\/transportjournal.com\/fr\/","name":"ITJ | International Transport Journal","description":"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. ","publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa","name":"Jeremy Soland","url":"https:\/\/transportjournal.com\/fr\/author\/jeremy\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/76049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/comments?post=76049"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/76049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/media\/76047"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/media?parent=76049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/categories?post=76049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/tags?post=76049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}