{"id":17404,"date":"2020-04-19T21:11:23","date_gmt":"2020-04-19T19:11:23","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/"},"modified":"2025-12-15T12:27:09","modified_gmt":"2025-12-15T11:27:09","slug":"le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/","title":{"rendered":"Le volume de fret dans le transport routier en Europe s&rsquo;effondre massivement"},"content":{"rendered":"<p>Le march\u00e9 du fret sur les routes europ\u00e9ennes a chut\u00e9 d&rsquo;environ deux tiers au cours du premier trimestre 2020, selon le barom\u00e8tre du fret de la bourse de fret Timocom. L&rsquo;ann\u00e9e avait pourtant bien commenc\u00e9. Ce n&rsquo;est qu&rsquo;\u00e0 la mi-mars que la grande chute a eu lieu, co\u00efncidant avec le d\u00e9but du confinement dans presque tous les pays europ\u00e9ens.<\/p>\n<p>(Erkrath) L&rsquo;incertitude quant \u00e0 l&rsquo;\u00e9volution de la crise du Corona a conduit en mars \u00e0 une augmentation soudaine des offres de fret sur le march\u00e9 du transport europ\u00e9en. \u00ab\u00a0De nombreuses entreprises ont anticip\u00e9 des fermetures de fronti\u00e8res et d&rsquo;autres restrictions li\u00e9es au Corona en passant des commandes \u00e0 l&rsquo;avance\u00a0\u00bb, commente Tilman Fecke, analyste commercial chez TIMOCOM, l&rsquo;augmentation exceptionnellement \u00e9lev\u00e9e des offres de fret qui ont \u00e9t\u00e9 publi\u00e9es sur la principale bourse de fret d&rsquo;Europe jusqu&rsquo;\u00e0 la mi-mars.<\/p>\n<p>Ainsi, TIMOCOM a enregistr\u00e9 une augmentation de 16 % des offres de fret au premier trimestre 2020 par rapport \u00e0 la m\u00eame p\u00e9riode de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente ; les transports en provenance des pays de l&rsquo;UE vers l&rsquo;Italie ont augment\u00e9 de 26 %, et vers la Pologne m\u00eame de 53 %. Les v\u00e9hicules frigorifiques \u00e9taient particuli\u00e8rement recherch\u00e9s. \u00c0 son apog\u00e9e, la demande de transports sous temp\u00e9rature contr\u00f4l\u00e9e \u00e9tait sup\u00e9rieure de 50 % aux valeurs de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente, rapporte l&rsquo;op\u00e9rateur de la bourse de fret.<\/p>\n<p><strong>Les volumes de fret ont chut\u00e9 de plus de deux tiers \u00e0 la mi-mars<\/strong><\/p>\n<p>Le point de basculement de la tendance \u00e0 la hausse est marqu\u00e9 \u00e0 partir de la mi-mars par le confinement \u00e0 l&rsquo;\u00e9chelle europ\u00e9enne, qui a largement conduit \u00e0 l&rsquo;arr\u00eat des entreprises de production et \u2013 \u00e0 l&rsquo;exception du commerce de d\u00e9tail alimentaire \u2013 \u00e0 un effondrement des volumes de livraison. \u00ab\u00a0Malgr\u00e9 l&rsquo;augmentation des transports dans le secteur alimentaire, les volumes de fret ont diminu\u00e9 de plus de deux tiers \u00e0 l&rsquo;\u00e9chelle europ\u00e9enne entre la mi-mars et la fin mars\u00a0\u00bb, rapporte Fecke. \u00ab\u00a0Une \u00e9volution comparable ne s&rsquo;est jamais produite avant P\u00e2ques.\u00a0\u00bb Jusqu&rsquo;\u00e0 750 000 offres de fret et d&rsquo;espace de chargement sont normalement publi\u00e9es quotidiennement sur TIMOCOM.<\/p>\n<p>Bien que les entreprises de transport cherchent d\u00e9sesp\u00e9r\u00e9ment des commandes pendant le confinement pour remplir leurs camions, les capacit\u00e9s de fret mises sur le march\u00e9 via TIMOCOM ont diminu\u00e9 au premier trimestre de cette ann\u00e9e. Ainsi, le nombre de camions disponibles a diminu\u00e9 de 3 % au premier trimestre par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente ; en Allemagne, le nombre d&rsquo;offres de v\u00e9hicules a m\u00eame chut\u00e9 de 15 %. Comment expliquer cela ?<\/p>\n<p>\u00ab\u00a0Nous observons que les entreprises de transport retirent temporairement une partie de leur flotte du march\u00e9 en raison d&rsquo;un manque de charge\u00a0\u00bb, commente Gunnar Gburek, porte-parole de TIMOCOM. Ainsi, l&rsquo;\u00e9tat d&rsquo;urgence dans lequel se trouve le monde ces semaines-ci entra\u00eene des distorsions du march\u00e9. N\u00e9anmoins, Gburek se montre optimiste : \u00ab\u00a0Actuellement, des tendances \u00e0 la hausse l\u00e9g\u00e8res se dessinent dans l&rsquo;offre de fret. Cependant, il ne sera possible de voir comment l&rsquo;industrie du transport \u00e9voluera sous l&rsquo;effet de la pand\u00e9mie de Corona qu&rsquo;au cours du deuxi\u00e8me trimestre.\u00a0\u00bb<\/p>\n<p>Avec le <a href=\"https:\/\/www.timocom.de\/services\/transportbarometer\" target=\"_blank\" rel=\"noopener noreferrer\">barom\u00e8tre du transport<\/a>, l&rsquo;entreprise FreightTech TIMOCOM analyse depuis 2009 l&rsquo;\u00e9volution de l&rsquo;offre et de la demande de transport de la bourse de fret int\u00e9gr\u00e9e dans le syst\u00e8me Smart Logistics. Plus de 130 000 utilisateurs g\u00e9n\u00e8rent ainsi jusqu&rsquo;\u00e0 750 000 offres de fret et d&rsquo;espace de chargement internationales chaque jour. Le syst\u00e8me aide les plus de 43 000 clients de TIMOCOM \u00e0 atteindre leurs objectifs logistiques de mani\u00e8re intelligente, s\u00fbre et simple.<\/p>\n<p>Graphique : Timocom<\/p>\n<p><a href=\"https:\/\/www.timocom.de\">www.timocom.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le march\u00e9 du fret sur les routes europ\u00e9ennes a chut\u00e9 d&rsquo;environ deux tiers au cours du premier trimestre 2020, selon le barom\u00e8tre du fret de la<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-17404","post","type-post","status-publish","format-standard","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le volume de fret dans le transport routier en Europe s&#039;effondre massivement - ITJ | International Transport Journal.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le volume de fret dans le transport routier en Europe s&#039;effondre massivement - ITJ | International Transport Journal.\" \/>\n<meta property=\"og:description\" content=\"Le march\u00e9 du fret sur les routes europ\u00e9ennes a chut\u00e9 d&rsquo;environ deux tiers au cours du premier trimestre 2020, selon le barom\u00e8tre du fret de la [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-19T19:11:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:27:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le volume de fret dans le transport routier en Europe s&rsquo;effondre massivement\",\"datePublished\":\"2020-04-19T19:11:23+00:00\",\"dateModified\":\"2025-12-15T11:27:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/\"},\"wordCount\":638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/\",\"name\":\"Le volume de fret dans le transport routier en Europe s'effondre massivement - ITJ | International Transport Journal.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-04-19T19:11:23+00:00\",\"dateModified\":\"2025-12-15T11:27:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/19\\\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le volume de fret dans le transport routier en Europe s&#8217;effondre massivement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. \",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le volume de fret dans le transport routier en Europe s'effondre massivement - ITJ | International Transport Journal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/","og_locale":"fr_FR","og_type":"article","og_title":"Le volume de fret dans le transport routier en Europe s'effondre massivement - ITJ | International Transport Journal.","og_description":"Le march\u00e9 du fret sur les routes europ\u00e9ennes a chut\u00e9 d&rsquo;environ deux tiers au cours du premier trimestre 2020, selon le barom\u00e8tre du fret de la [\u2026]","og_url":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-04-19T19:11:23+00:00","article_modified_time":"2025-12-15T11:27:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/"},"author":{"name":"","@id":""},"headline":"Le volume de fret dans le transport routier en Europe s&rsquo;effondre massivement","datePublished":"2020-04-19T19:11:23+00:00","dateModified":"2025-12-15T11:27:09+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/"},"wordCount":638,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"articleSection":["Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/","url":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/","name":"Le volume de fret dans le transport routier en Europe s'effondre massivement - ITJ | International Transport Journal.","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/#website"},"datePublished":"2020-04-19T19:11:23+00:00","dateModified":"2025-12-15T11:27:09+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/19\/le-volume-de-fret-dans-le-transport-routier-en-europe-seffondre-massivement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le volume de fret dans le transport routier en Europe s&#8217;effondre massivement"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/fr\/#website","url":"https:\/\/transportjournal.com\/fr\/","name":"ITJ | International Transport Journal","description":"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. ","publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/comments?post=17404"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17404\/revisions"}],"predecessor-version":[{"id":31158,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17404\/revisions\/31158"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/media?parent=17404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/categories?post=17404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/tags?post=17404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}