{"id":17386,"date":"2020-04-16T21:45:34","date_gmt":"2020-04-16T19:45:34","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/"},"modified":"2025-12-15T12:27:03","modified_gmt":"2025-12-15T11:27:03","slug":"chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/","title":{"rendered":"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web"},"content":{"rendered":"<p>La Journ\u00e9e de la Logistique de cette ann\u00e9e, organis\u00e9e par la BVL, l&rsquo;Association f\u00e9d\u00e9rale de logistique, s&rsquo;est d\u00e9roul\u00e9e dans un cadre particulier en raison de la pand\u00e9mie de Corona, \u00e0 savoir exclusivement en ligne. Parmi les nombreux \u00e9v\u00e9nements \u00e0 travers l&rsquo;Europe, voici le rapport de la journ\u00e9e de l&rsquo;entreprise de transport F.W. Neukirch de Br\u00eame dans son texte original.<\/p>\n<p style=\"text-align: center\">De F.W. Neukrich<\/p>\n<p>(Bremen) Logistique virtuelle, fantastique et vivante - la Journ\u00e9e de la Logistique (TdL) a \u00e9t\u00e9 un tout nouveau d\u00e9fi cette ann\u00e9e. Tr\u00e8s t\u00f4t, il \u00e9tait clair pour nous tous qu&rsquo;il n&rsquo;y aurait pas de \u00ab\u00a0journ\u00e9e normale\u00a0\u00bb avec des pr\u00e9sentations sur place et des visites d&rsquo;entrep\u00f4ts. La pand\u00e9mie de Corona a mis un terme \u00e0 nos plans et \u00e0 ceux de tous les autres participants au TdL. Mais les apprentis de FWN ne se sont pas laiss\u00e9s d\u00e9courager et ont rapidement d\u00e9plac\u00e9 la Journ\u00e9e de la Logistique de FWN vers les r\u00e9seaux sociaux. Les pr\u00e9sentations de chacun ont \u00e9t\u00e9 tr\u00e8s appr\u00e9ci\u00e9es. Notre objectif de susciter l&rsquo;enthousiasme des jeunes pour une formation dans le domaine de la logistique - bien s\u00fbr chez FWN - a \u00e9t\u00e9 pleinement atteint. Les nombreuses r\u00e9actions positives sur Internet montrent qu&rsquo;il a \u00e9galement atteint de nombreux autres passionn\u00e9s de logistique.<\/p>\n<p>La BVL (Association f\u00e9d\u00e9rale de logistique) en tant qu&rsquo;initiatrice de la journ\u00e9e a montr\u00e9 d&rsquo;autres voies vari\u00e9es pour utiliser cette journ\u00e9e dans le but de promouvoir l&rsquo;image du secteur \u00e9conomique. Gr\u00e2ce \u00e0 la diversit\u00e9 des formats d&rsquo;\u00e9v\u00e9nements virtuels, de webinaires, de visites, de salons, de conf\u00e9rences, de vid\u00e9os et de soir\u00e9es de visionnage, souvent organis\u00e9s \u00e0 la derni\u00e8re minute, nous avons pu int\u00e9resser et enthousiasmer de nombreuses personnes pour la logistique. Tous les participants ont atteint environ 800 000 personnes sur Internet !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2758 size-full\" src=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/FW_Neukirch_20.4.20_2.jpg\" alt=\"\" width=\"879\" height=\"474\" \/><\/p>\n<p>La Journ\u00e9e en ligne \u00e9tait diff\u00e9rente, mais passionnante. L&rsquo;\u00e9v\u00e9nement \u00e9tait fermement entre les mains des apprentis. Tout a parfaitement fonctionn\u00e9 - de A \u00e0 Z. Merci \u00e9galement \u00e0 tous les autres qui ont soutenu la journ\u00e9e. Les futurs professionnels de la logistique ont \u00e0 nouveau tout donn\u00e9 cette ann\u00e9e. Un \u00e9loge \u00e0 ce stade devrait encore motiver \u00e0 redevenir actif l&rsquo;ann\u00e9e prochaine.<\/p>\n<p>Pour cet engagement, la direction remercie tous ceux qui ont \u0153uvr\u00e9 en coulisses sur le plan organisationnel et technique, permettant ainsi \u00e0 la Journ\u00e9e de la Logistique 2020 de devenir un \u00e9v\u00e9nement r\u00e9ussi.<\/p>\n<p>La barre pour la Journ\u00e9e de la Logistique 2021 est \u00e0 nouveau un peu plus haute - restez \u00e0 l&rsquo;aff\u00fbt de l&rsquo;ann\u00e9e \u00e0 venir ! Et esp\u00e9rons qu&rsquo;il y aura \u00e0 nouveau de la logistique \u00e0 port\u00e9e de main.<\/p>\n<p>Restez curieux de la logistique. Et surtout - restez en bonne sant\u00e9.<\/p>\n<p>Photos : F.W. Neukirch<\/p>\n<p><a href=\"https:\/\/neukirch.de\/\">https:\/\/neukirch.de\/<\/a> \u00a0-\u00a0 <a href=\"https:\/\/www.tag-der-logistik.de\/\">https:\/\/www.tag-der-logistik.de\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Journ\u00e9e de la Logistique de cette ann\u00e9e, organis\u00e9e par la BVL, l&rsquo;Association f\u00e9d\u00e9rale de logistique, s&rsquo;est d\u00e9roul\u00e9e dans un cadre particulier en raison de la<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-17386","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web - ITJ | International Transport Journal.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web - ITJ | International Transport Journal.\" \/>\n<meta property=\"og:description\" content=\"La Journ\u00e9e de la Logistique de cette ann\u00e9e, organis\u00e9e par la BVL, l&rsquo;Association f\u00e9d\u00e9rale de logistique, s&rsquo;est d\u00e9roul\u00e9e dans un cadre particulier en raison de la [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T19:45:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:27:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/05\/Schiff_Container_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1901\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web\",\"datePublished\":\"2020-04-16T19:45:34+00:00\",\"dateModified\":\"2025-12-15T11:27:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/FW_Neukirch_20.4.20_2.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/\",\"name\":\"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web - ITJ | International Transport Journal.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/FW_Neukirch_20.4.20_2.jpg\",\"datePublished\":\"2020-04-16T19:45:34+00:00\",\"dateModified\":\"2025-12-15T11:27:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/FW_Neukirch_20.4.20_2.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/FW_Neukirch_20.4.20_2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/04\\\/16\\\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. \",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web - ITJ | International Transport Journal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/","og_locale":"fr_FR","og_type":"article","og_title":"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web - ITJ | International Transport Journal.","og_description":"La Journ\u00e9e de la Logistique de cette ann\u00e9e, organis\u00e9e par la BVL, l&rsquo;Association f\u00e9d\u00e9rale de logistique, s&rsquo;est d\u00e9roul\u00e9e dans un cadre particulier en raison de la [\u2026]","og_url":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-04-16T19:45:34+00:00","article_modified_time":"2025-12-15T11:27:03+00:00","og_image":[{"width":1901,"height":898,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/05\/Schiff_Container_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/"},"author":{"name":"","@id":""},"headline":"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web","datePublished":"2020-04-16T19:45:34+00:00","dateModified":"2025-12-15T11:27:03+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/FW_Neukirch_20.4.20_2.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/","url":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/","name":"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web - ITJ | International Transport Journal.","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/FW_Neukirch_20.4.20_2.jpg","datePublished":"2020-04-16T19:45:34+00:00","dateModified":"2025-12-15T11:27:03+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/FW_Neukirch_20.4.20_2.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/FW_Neukirch_20.4.20_2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/fr\/2020\/04\/16\/chez-f-w-neukirch-les-apprentis-deplacent-la-journee-de-la-logistique-sur-le-web\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Chez F.W. Neukirch, les apprentis d\u00e9placent la Journ\u00e9e de la Logistique sur le Web"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/fr\/#website","url":"https:\/\/transportjournal.com\/fr\/","name":"ITJ | International Transport Journal","description":"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. ","publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/comments?post=17386"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17386\/revisions"}],"predecessor-version":[{"id":31122,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17386\/revisions\/31122"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/media?parent=17386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/categories?post=17386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/tags?post=17386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}