{"id":17079,"date":"2020-02-06T06:31:43","date_gmt":"2020-02-06T05:31:43","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/"},"modified":"2025-12-15T12:25:59","modified_gmt":"2025-12-15T11:25:59","slug":"rhenus-acquiert-le-prestataire-logistique-espagnol-ltk","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/","title":{"rendered":"Rhenus acquiert le prestataire logistique espagnol LTK"},"content":{"rendered":"<p>\u00c0 partir du 27 janvier, le groupe Rhenus a acquis l&rsquo;entreprise espagnole LTK. Le sp\u00e9cialiste int\u00e9gr\u00e9 de la cha\u00eene d&rsquo;approvisionnement poss\u00e8de, en plus de son si\u00e8ge \u00e0 Madrid, des capacit\u00e9s d&rsquo;entreposage dans trois autres sites en Espagne. L&rsquo;accent de ses activit\u00e9s est mis sur des solutions logistiques pour l&rsquo;a\u00e9rospatiale et l&rsquo;industrie automobile.<\/p>\n<p>(Holzwickede, 06.02.2020) Fond\u00e9e en 2002, l&rsquo;entreprise LTK est aujourd&rsquo;hui pr\u00e9sente dans la capitale espagnole, \u00e0 \u00c1lava au Pays basque, ainsi qu&rsquo;aux sites andalous de S\u00e9ville et de Cadix. Au total, plus de 26 000 m\u00e8tres carr\u00e9s de capacit\u00e9s d&rsquo;entreposage sont disponibles. Parmi les clients figurent Airbus Group et Alestis Aerospace. En plus de l&rsquo;entreposage, LTK propose des services de gestion de la cha\u00eene d&rsquo;approvisionnement, de logistique d&rsquo;approvisionnement, de retour et de pi\u00e8ces de rechange, de contr\u00f4les de qualit\u00e9, ainsi que de traitement industriel et de traitement au sol des avions. Le prestataire logistique effectue chaque ann\u00e9e plus de 110 000 contr\u00f4les techniques pour ses clients. Depuis 2004, LTK \u00e0 Cadix et S\u00e9ville approvisionne les sites de production d&rsquo;Airbus. Les entrep\u00f4ts logistiques enregistrent plus d&rsquo;un million de mouvements de marchandises entrants et sortants par an.\u00ab Les sites d&rsquo;entreposage de LTK constitueront \u00e0 l&rsquo;avenir la base pour le d\u00e9veloppement ult\u00e9rieur des solutions d&rsquo;entreposage Rhenus en Espagne. Ensemble, nous esp\u00e9rons des opportunit\u00e9s de croissance dans le secteur a\u00e9rospatial espagnol. De plus, nous pouvons entrer sur le march\u00e9 a\u00e9ronautique europ\u00e9en avec le savoir-faire nouvellement acquis et le soutien de LTK \u00bb, d\u00e9clare Andreas Plikat, directeur g\u00e9n\u00e9ral de Rhenus Warehousing Solutions Europe. Les sites de LTK sont certifi\u00e9s selon la norme EN 9120, une norme pour les commer\u00e7ants et les entreposeurs dans l&rsquo;a\u00e9ronautique, l&rsquo;a\u00e9rospatial et la d\u00e9fense, ainsi que selon ISO 9001 (gestion de la qualit\u00e9), ISO\/IEC 27001 (s\u00e9curit\u00e9 de l&rsquo;information) et ISO 14001 (gestion environnementale).<\/p>\n<p>\u00c0 propos de Rhenus<\/p>\n<p>Le groupe Rhenus est l&rsquo;un des principaux prestataires logistiques op\u00e9rant \u00e0 l&rsquo;\u00e9chelle mondiale, avec un chiffre d&rsquo;affaires annuel de 5,1 milliards d&rsquo;euros. 31 000 employ\u00e9s de Rhenus sont pr\u00e9sents sur 660 sites. Tout au long de la cha\u00eene d&rsquo;approvisionnement, le groupe Rhenus propose des solutions pour divers secteurs, y compris le transport multimodal, l&rsquo;entreposage, le d\u00e9douanement et des services \u00e0 valeur ajout\u00e9e innovants. Photo : Rhenus\/LTK <a href=\"https:\/\/www.rhenus.group\/de\" target=\"_blank\" rel=\"noopener noreferrer\">www.rhenus.com<\/a> - <a href=\"https:\/\/www.ltkgrp.com\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.ltkgrp.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 partir du 27 janvier, le groupe Rhenus a acquis l&rsquo;entreprise espagnole LTK. Le sp\u00e9cialiste int\u00e9gr\u00e9 de la cha\u00eene d&rsquo;approvisionnement poss\u00e8de, en plus de son si\u00e8ge<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-17079","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rhenus acquiert le prestataire logistique espagnol LTK - ITJ | International Transport Journal.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rhenus acquiert le prestataire logistique espagnol LTK - ITJ | International Transport Journal.\" \/>\n<meta property=\"og:description\" content=\"\u00c0 partir du 27 janvier, le groupe Rhenus a acquis l&rsquo;entreprise espagnole LTK. Le sp\u00e9cialiste int\u00e9gr\u00e9 de la cha\u00eene d&rsquo;approvisionnement poss\u00e8de, en plus de son si\u00e8ge [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-06T05:31:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:25:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rhenus acquiert le prestataire logistique espagnol LTK\",\"datePublished\":\"2020-02-06T05:31:43+00:00\",\"dateModified\":\"2025-12-15T11:25:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/\"},\"wordCount\":422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/\",\"name\":\"Rhenus acquiert le prestataire logistique espagnol LTK - ITJ | International Transport Journal.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-02-06T05:31:43+00:00\",\"dateModified\":\"2025-12-15T11:25:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/2020\\\/02\\\/06\\\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rhenus acquiert le prestataire logistique espagnol LTK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. \",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rhenus acquiert le prestataire logistique espagnol LTK - ITJ | International Transport Journal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/","og_locale":"fr_FR","og_type":"article","og_title":"Rhenus acquiert le prestataire logistique espagnol LTK - ITJ | International Transport Journal.","og_description":"\u00c0 partir du 27 janvier, le groupe Rhenus a acquis l&rsquo;entreprise espagnole LTK. Le sp\u00e9cialiste int\u00e9gr\u00e9 de la cha\u00eene d&rsquo;approvisionnement poss\u00e8de, en plus de son si\u00e8ge [\u2026]","og_url":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-02-06T05:31:43+00:00","article_modified_time":"2025-12-15T11:25:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/"},"author":{"name":"","@id":""},"headline":"Rhenus acquiert le prestataire logistique espagnol LTK","datePublished":"2020-02-06T05:31:43+00:00","dateModified":"2025-12-15T11:25:59+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/"},"wordCount":422,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/","url":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/","name":"Rhenus acquiert le prestataire logistique espagnol LTK - ITJ | International Transport Journal.","isPartOf":{"@id":"https:\/\/transportjournal.com\/fr\/#website"},"datePublished":"2020-02-06T05:31:43+00:00","dateModified":"2025-12-15T11:25:59+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/fr\/2020\/02\/06\/rhenus-acquiert-le-prestataire-logistique-espagnol-ltk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Rhenus acquiert le prestataire logistique espagnol LTK"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/fr\/#website","url":"https:\/\/transportjournal.com\/fr\/","name":"ITJ | International Transport Journal","description":"Restez inform\u00e9 des derni\u00e8res nouvelles mondiales dans les secteurs du transport, de la logistique et de la cha\u00eene d'approvisionnement. Transport Journal fournit des informations d'experts, des analyses et des mises \u00e0 jour sur le transport maritime, l'aviation, l'intermodalit\u00e9 et l'exp\u00e9dition. ","publisher":{"@id":"https:\/\/transportjournal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/comments?post=17079"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17079\/revisions"}],"predecessor-version":[{"id":30555,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/posts\/17079\/revisions\/30555"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/media?parent=17079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/categories?post=17079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/fr\/wp-json\/wp\/v2\/tags?post=17079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}