{"id":75306,"date":"2026-01-30T10:32:43","date_gmt":"2026-01-30T10:32:43","guid":{"rendered":"https:\/\/transportjournal.com\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/"},"modified":"2026-01-30T10:32:43","modified_gmt":"2026-01-30T10:32:43","slug":"cambio-de-liderazgo-en-id-logistics-benelux","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/","title":{"rendered":"Cambio de liderazgo en ID Logistics Benelux"},"content":{"rendered":"<p>ID Logistics ha anunciado varios cambios en la direcci\u00f3n de la empresa en la regi\u00f3n de Benelux y en Canad\u00e1 para apoyar el crecimiento de la empresa. Marco van Walraven (izquierda), hasta ahora director general de ID Logistics Benelux, asumir\u00e1 ahora el cargo de director general de ID Logistics Canad\u00e1.<\/p>\n<p>Marco van Walraven aporta m\u00e1s de 20 a\u00f1os de experiencia en la cadena de suministro y la log\u00edstica contractual. Se uni\u00f3 al grupo ID Logistics en 2017 y desde entonces ha desempe\u00f1ado un papel clave en el desarrollo y la estructuraci\u00f3n de las actividades en la regi\u00f3n de Benelux. Con un MBA y una formaci\u00f3n especializada en log\u00edstica y cadena de suministro, asumir\u00e1 ahora la responsabilidad del reci\u00e9n lanzado mercado canadiense y apoyar\u00e1 las operaciones all\u00ed.<\/p>\n<h3>Nueva direcci\u00f3n para ID Logistics Benelux<\/h3>\n<p>Bart Coenen ha sido nombrado nuevo director general de ID Logistics Benelux. Anteriormente, se desempe\u00f1\u00f3 como director de las actividades de log\u00edstica contractual en la regi\u00f3n de Benelux. Coenen ha acumulado muchos a\u00f1os de experiencia en DB Schenker, donde ocup\u00f3 varios puestos de liderazgo en log\u00edstica contractual. Tiene una maestr\u00eda en gesti\u00f3n con especializaci\u00f3n en ingenier\u00eda y cadena de suministro, y aporta amplios conocimientos en la direcci\u00f3n de organizaciones complejas y en el desarrollo de soluciones que generan valor. En su nuevo rol, consolidar\u00e1 a\u00fan m\u00e1s la din\u00e1mica de ID Logistics en los Pa\u00edses Bajos, centr\u00e1ndose en el rendimiento operativo, la orientaci\u00f3n al cliente y el compromiso de los empleados. Este nombramiento es parte de una estrategia para fomentar el talento interno y garantizar una estructura de gesti\u00f3n continua.<\/p>\n<p>Los cambios en la direcci\u00f3n de la empresa subrayan el compromiso de ID Logistics de aprovechar la experiencia de sus equipos y fortalecer la coherencia de las organizaciones para impulsar el crecimiento de la empresa. ID Logistics, bajo la direcci\u00f3n de Eric H\u00e9mar, es una empresa internacional en el \u00e1mbito de la log\u00edstica contractual y alcanz\u00f3 una facturaci\u00f3n de 3,7 mil millones de EUR en 2025. La empresa opera m\u00e1s de 450 ubicaciones en 19 pa\u00edses y emplea a alrededor de 50,000 personas. ID Logistics se ha destacado por su cartera de clientes equilibrada en los sectores de distribuci\u00f3n, comercio electr\u00f3nico, as\u00ed como bienes de consumo, cosm\u00e9ticos y moda, y sigue una ambiciosa pol\u00edtica de RSE.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.id-logistics.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.id-logistics.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ID Logistics ha nombrado nuevos directores generales para la regi\u00f3n de Benelux y Canad\u00e1, con el fin de apoyar el crecimiento de la empresa a trav\u00e9s de l\u00edderes experimentados.<\/p>\n","protected":false},"author":12,"featured_media":75303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1614,1611,1603,1605],"tags":[11474,11475,11476,11477,3130,2548,11478,11479,11480,11481,2651,10067,5090,5091,10069,1889,2007,2123,2562,11482,2279,2280,11483,11484,11485,10562,2133,1831,10563,3151,5108,2282,11486,11487,11488,11489,11490,4139,3602,11491,11492,2148,2237,11493,2106,2157,1774,11494],"class_list":["post-75306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-america","category-europa","category-personas-y-empresas","category-expedicion-y-logistica","tag-bart-coenen","tag-benelux","tag-canada","tag-changement-de-direction","tag-contract-logistics","tag-corporate-governance","tag-croissance-dans-le-secteur-logistique","tag-csr-policy","tag-csr-politik","tag-customer-orientation","tag-db-schenker","tag-deutsch-id-logistics","tag-e-commerce-logistics","tag-e-commerce-logistik","tag-entreprises-de-logistique","tag-fachkraeftemangel","tag-fuehrungskraeftewechsel","tag-gestion-de-la-chaine-dapprovisionnement","tag-gouvernance-dentreprise","tag-growth-in-logistics-sector","tag-international-logistics","tag-internationale-logistik","tag-kanada","tag-kundenorientierung","tag-leadership-change","tag-logistics-companies","tag-logistics-service-providers","tag-logistikdienstleister","tag-logistikunternehmen","tag-logistique-contractuelle","tag-logistique-e-commerce","tag-logistique-internationale","tag-management-structure-francais-id-logistics","tag-managementstruktur-english-id-logistics","tag-marco-van-walraven","tag-operational-performance","tag-operative-leistung","tag-orientation-client","tag-penurie-de-competences","tag-performance-operationnelle","tag-politique-rse","tag-prestataires-de-services-logistiques","tag-skills-shortage","tag-structure-de-gestion","tag-supply-chain-management","tag-unternehmensfuehrung","tag-vertragslogistik","tag-wachstum-im-logistiksektor"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambio de liderazgo en ID Logistics Benelux - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambio de liderazgo en ID Logistics Benelux - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"ID Logistics ha nombrado nuevos directores generales para la regi\u00f3n de Benelux y Canad\u00e1, con el fin de apoyar el crecimiento de la empresa a trav\u00e9s de l\u00edderes experimentados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T10:32:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/01\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png\" \/>\n\t<meta property=\"og:image:width\" content=\"579\" \/>\n\t<meta property=\"og:image:height\" content=\"326\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"Cambio de liderazgo en ID Logistics Benelux\",\"datePublished\":\"2026-01-30T10:32:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/\"},\"wordCount\":421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png\",\"keywords\":[\"Bart Coenen\",\"Benelux\",\"Canada\",\"changement de direction\",\"contract logistics\",\"corporate governance\",\"croissance dans le secteur logistique\",\"CSR policy\",\"CSR-Politik\",\"customer orientation\",\"DB Schenker\",\"Deutsch ID Logistics\",\"e-commerce logistics\",\"E-Commerce Logistik\",\"entreprises de logistique\",\"Fachkr\u00e4ftemangel\",\"F\u00fchrungskr\u00e4ftewechsel\",\"gestion de la cha\u00eene d'approvisionnement\",\"gouvernance d'entreprise\",\"growth in logistics sector\",\"international logistics\",\"internationale Logistik\",\"Kanada\",\"Kundenorientierung\",\"leadership change\",\"logistics companies\",\"logistics service providers\",\"Logistikdienstleister\",\"Logistikunternehmen\",\"logistique contractuelle\",\"logistique e-commerce\",\"logistique internationale\",\"management structure Fran\u00e7ais ID Logistics\",\"Managementstruktur English ID Logistics\",\"Marco van Walraven\",\"operational performance\",\"operative Leistung\",\"orientation client\",\"p\u00e9nurie de comp\u00e9tences\",\"performance op\u00e9rationnelle\",\"politique RSE\",\"prestataires de services logistiques\",\"skills shortage\",\"structure de gestion\",\"Supply Chain Management\",\"Unternehmensf\u00fchrung\",\"Vertragslogistik\",\"Wachstum im Logistiksektor\"],\"articleSection\":[\"Am\u00e9rica\",\"Europa\",\"Personas y empresas\",\"Transporte de mercanc\u00edas y log\u00edstica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/\",\"name\":\"Cambio de liderazgo en ID Logistics Benelux - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png\",\"datePublished\":\"2026-01-30T10:32:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png\",\"width\":579,\"height\":326},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2026\\\/01\\\/30\\\/cambio-de-liderazgo-en-id-logistics-benelux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambio de liderazgo en ID Logistics Benelux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambio de liderazgo en ID Logistics Benelux - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/","og_locale":"es_ES","og_type":"article","og_title":"Cambio de liderazgo en ID Logistics Benelux - ITJ | International Transport Journal","og_description":"ID Logistics ha nombrado nuevos directores generales para la regi\u00f3n de Benelux y Canad\u00e1, con el fin de apoyar el crecimiento de la empresa a trav\u00e9s de l\u00edderes experimentados.","og_url":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2026-01-30T10:32:43+00:00","og_image":[{"width":579,"height":326,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/01\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png","type":"image\/png"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andreas Haug","Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/transportjournal.com\/es\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"Cambio de liderazgo en ID Logistics Benelux","datePublished":"2026-01-30T10:32:43+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/"},"wordCount":421,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/es\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/01\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png","keywords":["Bart Coenen","Benelux","Canada","changement de direction","contract logistics","corporate governance","croissance dans le secteur logistique","CSR policy","CSR-Politik","customer orientation","DB Schenker","Deutsch ID Logistics","e-commerce logistics","E-Commerce Logistik","entreprises de logistique","Fachkr\u00e4ftemangel","F\u00fchrungskr\u00e4ftewechsel","gestion de la cha\u00eene d'approvisionnement","gouvernance d'entreprise","growth in logistics sector","international logistics","internationale Logistik","Kanada","Kundenorientierung","leadership change","logistics companies","logistics service providers","Logistikdienstleister","Logistikunternehmen","logistique contractuelle","logistique e-commerce","logistique internationale","management structure Fran\u00e7ais ID Logistics","Managementstruktur English ID Logistics","Marco van Walraven","operational performance","operative Leistung","orientation client","p\u00e9nurie de comp\u00e9tences","performance op\u00e9rationnelle","politique RSE","prestataires de services logistiques","skills shortage","structure de gestion","Supply Chain Management","Unternehmensf\u00fchrung","Vertragslogistik","Wachstum im Logistiksektor"],"articleSection":["Am\u00e9rica","Europa","Personas y empresas","Transporte de mercanc\u00edas y log\u00edstica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/","url":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/","name":"Cambio de liderazgo en ID Logistics Benelux - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/01\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png","datePublished":"2026-01-30T10:32:43+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/01\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2026\/01\/CP20260129-ID-Logistics-Nominations-Marco-Van-Walraven-Bart-Coenen-650-361-aspect-ratio-1400-788.png","width":579,"height":326},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/es\/2026\/01\/30\/cambio-de-liderazgo-en-id-logistics-benelux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cambio de liderazgo en ID Logistics Benelux"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/es\/#website","url":"https:\/\/transportjournal.com\/es\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/es\/#organization","name":"Grupo Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transportjournal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/es\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/transportjournal.com\/es\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/posts\/75306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/comments?post=75306"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/posts\/75306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/media\/75303"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/media?parent=75306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/categories?post=75306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/tags?post=75306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}