{"id":17111,"date":"2020-02-13T06:18:09","date_gmt":"2020-02-13T05:18:09","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/"},"modified":"2025-12-15T12:26:03","modified_gmt":"2025-12-15T11:26:03","slug":"establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/","title":{"rendered":"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand"},"content":{"rendered":"<p>El Ministro Federal Scheuer promete financiaci\u00f3n federal para el cruce K\u00f6hlbrand en Hamburgo. Se ha firmado una declaraci\u00f3n de intenciones conjunta con Peter Tschentscher, el Alcalde de Hamburgo. Son buenas noticias para la log\u00edstica.<\/p>\n<p>(Hamburgo, 13.02.2020) Para que el norte siga siendo m\u00f3vil: Andreas Scheuer, Ministro Federal de Transporte e Infraestructura Digital, ha firmado hoy una declaraci\u00f3n de intenciones conjunta sobre la renovaci\u00f3n del cruce K\u00f6hlbrand con Peter Tschentscher, Alcalde de la Ciudad Libre y Hanse\u00e1tica de Hamburgo. Al mismo tiempo, prometi\u00f3 financiaci\u00f3n federal. Esto tambi\u00e9n cuenta con el apoyo de R\u00fcdiger Kruse, ponente principal para Transporte e Infraestructura Digital en el Comit\u00e9 de Presupuesto del Bundestag, y Johannes Kahrs, portavoz del grupo parlamentario del SPD en el Comit\u00e9 de Presupuesto.Scheuer: \u00abEn el puerto de Hamburgo late el coraz\u00f3n econ\u00f3mico de Europa Central. Desde aqu\u00ed se transportan mercanc\u00edas y productos a todo el mundo. Es importante contar con una conexi\u00f3n eficiente a la red de carreteras alemana. El cruce K\u00f6hlbrand desempe\u00f1a un papel clave en esto, por lo que lo convertiremos en una carretera federal y queremos financiar la nueva construcci\u00f3n con fondos federales\u00bb.Tschentscher: \u00abLa log\u00edstica cumple una funci\u00f3n transversal para todos los sectores de nuestra econom\u00eda. El puente K\u00f6hlbrand ha aliviado durante d\u00e9cadas los tr\u00e1ficos econ\u00f3micos en los barrios del centro de la ciudad. Tiene varias d\u00e9cadas de antig\u00fcedad y debe ser reemplazado. Necesitamos un nuevo cruce K\u00f6hlbrand que asuma la funci\u00f3n actual y, al mismo tiempo, incorpore posibilidades innovadoras para el transporte de mercanc\u00edas. Aprecio la decisi\u00f3n del gobierno federal de participar en una soluci\u00f3n moderna\u00bb.Kruse: \u00abEl antiguo cruce K\u00f6hlbrand es uno de los s\u00edmbolos de Hamburgo y nos ha servido excelentemente en las \u00faltimas d\u00e9cadas. Ahora se trata de encontrar una buena soluci\u00f3n de sucesi\u00f3n, ya que la conexi\u00f3n es central para el puerto de Hamburgo y, por lo tanto, tambi\u00e9n tiene una gran importancia nacional\u00bb.Kahrs: \u00abCon el nuevo cruce K\u00f6hlbrand, el ramal del puerto y la continuaci\u00f3n de la A 26, el sur de Hamburgo se fortalecer\u00e1 significativamente en t\u00e9rminos de infraestructura. El puente K\u00f6hlbrand fue inaugurado en 1974 y conecta la isla del Elba Wilhelmsburg con la autopista federal 7. Con una longitud total de m\u00e1s de 3600 metros y una altura libre de 53 metros, es uno de los puentes de cables m\u00e1s conocidos de Alemania. Al mismo tiempo, el puente K\u00f6hlbrand es uno de los ejes de tr\u00e1fico m\u00e1s importantes sobre el S\u00fcderelbe: a trav\u00e9s de \u00e9l se maneja una parte considerable del tr\u00e1fico de larga distancia y econ\u00f3mico relacionado con el puerto. Adem\u00e1s, conecta las partes occidental y oriental del puerto. Se pronostica que el final de la vida \u00fatil del actual puente K\u00f6hlbrand ser\u00e1 en 2030. Hamburgo ya ha encargado un estudio de viabilidad para la planificaci\u00f3n de un nuevo cruce K\u00f6hlbrand. Este examina como posibles variantes la construcci\u00f3n de un puente de reemplazo as\u00ed como la nueva construcci\u00f3n de un t\u00fanel\u00bb. www.bmvi.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministro Federal Scheuer promete financiaci\u00f3n federal para el cruce K\u00f6hlbrand en Hamburgo. Se ha firmado una declaraci\u00f3n de intenciones conjunta con Peter Tschentscher, el Alcalde<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-17111","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"El Ministro Federal Scheuer promete financiaci\u00f3n federal para el cruce K\u00f6hlbrand en Hamburgo. Se ha firmado una declaraci\u00f3n de intenciones conjunta con Peter Tschentscher, el Alcalde [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-13T05:18:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:26:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand\",\"datePublished\":\"2020-02-13T05:18:09+00:00\",\"dateModified\":\"2025-12-15T11:26:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/\"},\"wordCount\":553,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/\",\"name\":\"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#website\"},\"datePublished\":\"2020-02-13T05:18:09+00:00\",\"dateModified\":\"2025-12-15T11:26:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/2020\\\/02\\\/13\\\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/","og_locale":"es_ES","og_type":"article","og_title":"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand - ITJ | International Transport Journal","og_description":"El Ministro Federal Scheuer promete financiaci\u00f3n federal para el cruce K\u00f6hlbrand en Hamburgo. Se ha firmado una declaraci\u00f3n de intenciones conjunta con Peter Tschentscher, el Alcalde [\u2026]","og_url":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-02-13T05:18:09+00:00","article_modified_time":"2025-12-15T11:26:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/"},"author":{"name":"","@id":""},"headline":"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand","datePublished":"2020-02-13T05:18:09+00:00","dateModified":"2025-12-15T11:26:03+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/"},"wordCount":553,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/","url":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/","name":"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/es\/#website"},"datePublished":"2020-02-13T05:18:09+00:00","dateModified":"2025-12-15T11:26:03+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/es\/2020\/02\/13\/establecimiento-de-condiciones-para-la-nueva-construccion-del-cruce-kohlbrand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Establecimiento de condiciones para la nueva construcci\u00f3n del cruce K\u00f6hlbrand"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/es\/#website","url":"https:\/\/transportjournal.com\/es\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/es\/#organization","name":"Grupo Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/transportjournal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/posts\/17111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/comments?post=17111"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/posts\/17111\/revisions"}],"predecessor-version":[{"id":30619,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/posts\/17111\/revisions\/30619"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/media?parent=17111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/categories?post=17111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/es\/wp-json\/wp\/v2\/tags?post=17111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}