{"id":4796,"date":"2025-07-04T17:15:58","date_gmt":"2025-07-04T15:15:58","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/"},"modified":"2025-07-04T17:15:58","modified_gmt":"2025-07-04T15:15:58","slug":"db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/","title":{"rendered":"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb"},"content":{"rendered":"<h5><strong>Erstmals wurde in Europa eine G\u00fcterzuglokomotive f\u00fcr den automatisierten Regelbetrieb umger\u00fcstet: DB Cargo hat im Werk K\u00f6ln-Gremberg die erste Strecken-Lok mit modernsten Technologien f\u00fcr Automatic Train Operation (ATO) und Remote Train Operation (RTO) ausgestattet. Damit erreicht Europas gr\u00f6\u00dfte G\u00fcterbahn gemeinsam mit dem Deutschen Zentrum f\u00fcr Luft- und Raumfahrt (DLR) sowie den Partnern Hitachi und Remoot einen wichtigen Meilenstein in einem wegweisenden Pilotprojekt. <\/strong><\/h5>\n<p>(Mainz\/K\u00f6ln) Das Ziel ist klar - ATO und RTO sollen europaweit den G\u00fcterverkehr auf der Schiene effizienter, flexibler und wettbewerbsf\u00e4higer machen.\u00a0Das Projekt ist Teil des Bundesprogramms \u201eZukunft Schieneng\u00fcterverkehr zur F\u00f6rderung von Innovationen\u201c, mit dem das Bundesministerium f\u00fcr Verkehr (BMV) die Entwicklung und zeitnahe Markteinf\u00fchrung innovativer Technologien im G\u00fcterverkehr beschleunigen und so den Marktanteil der Schiene am G\u00fcterverkehr in Deutschland steigern m\u00f6chte. In dieses Projekt flossen dabei Bundesmittel in H\u00f6he von 18,86 Millionen Euro.<\/p>\n<h5>Einj\u00e4hrige Erprobungsphase ab Oktober 2025<\/h5>\n<p>Ab Oktober 2025 beginnt eine einj\u00e4hrige Erprobungsphase auf der niederl\u00e4ndischen Betuweroute \u2013 sie ist eine der wichtigsten und modernsten G\u00fcterverkehrsstrecken Europas. Im sogenannten ATO-Betrieb \u00fcbernimmt die Lok automatisiert Beschleunigung, Fahrt, Bremsung und Halt. Sicherheit bleibt dabei oberstes Gebot: Ein\/-e Lokf\u00fchrer\/-in bleibt an Bord, erg\u00e4nzt durch ein zentrales Fern\u00fcberwachungs- und Steuerungsteam. W\u00e4hrend des Probebetriebs werden Fahrten mit verschiedenen Wagentypen und Beladungsszenarien betrachtet \u2013 von schweren Sch\u00fcttgutwagen bis zu teilgef\u00fcllten Kesselwagen. Zudem wird erstmals die Kombination der Technologien ATO und RTO im offenen Netz erprobt.<\/p>\n<p>Dr. Sigrid Nikutta, Vorstand G\u00fcterverkehr der Deutschen Bahn AG und Vorsitzende des Vorstands der DB Cargo AG: \u201eAutomatisierte also selbstfahrende Loks nutzen die Gleise effizienter \u2013 so schaffen wir mehr Kapazit\u00e4t und bessere Qualit\u00e4t im Schieneng\u00fcterverkehr. Die Premiere dieser automatisierten Lok im Rangierbahnhof K\u00f6ln-Gremberg ist ein wichtiger Schritt f\u00fcr die Zukunft des europ\u00e4ischen G\u00fctertransports auf der Schiene.<\/p>\n<p>DB Cargo und der Schieneng\u00fcterverkehr sind ma\u00dfgeblich f\u00fcr das Gelingen der Verkehrswende und somit essentiell im Kampf gegen den Klimawandel. Denn die Verlagerung von G\u00fctern auf die Schiene ist der gr\u00f6\u00dfte und effektivste Hebel, um CO2 zu reduzieren und unsere Stra\u00dfen zu entlasten.\u201c<\/p>\n<p>Bundesminister f\u00fcr Verkehr Patrick Schnieder (CDU): \u201eInnovationen sind der Motor f\u00fcr einen modernen, intelligenten und effizienten Schieneng\u00fcterverkehr. Das automatisierte Fahren entlastet Besch\u00e4ftigte und schafft gleichsam zukunftsf\u00e4hige Arbeitspl\u00e4tze. Genau das brauchen wir, um dem Fachkr\u00e4ftemangel und dem demografischen Wandel zu begegnen, der nat\u00fcrlich auch vor dem Schieneng\u00fcterverkehr keinen Halt macht. Mit diesem Projekt leisten wir diesbez\u00fcglich Pionierarbeit f\u00fcr den gesamten Schieneng\u00fcterverkehr in Europa.\u201c<\/p>\n<h5>Digitalisierung im Schieneng\u00fcterverkehr vorantreiben<\/h5>\n<p>Die Automatisierung des Zugbetriebs wird mehr G\u00fcter von der Stra\u00dfe auf die Schiene verlagern \u2013 ist also ein zentraler Hebel f\u00fcr klimafreundliche Logistik in Europa. DB Cargo treibt damit die Digitalisierung und Automatisierung im Schieneng\u00fcterverkehr konsequent voran und leistet einen wichtigen Beitrag f\u00fcr die Verkehrs- und Klimawende.<\/p>\n<p>Foto: \u00a9 DB Cargo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erstmals wurde in Europa eine G\u00fcterzuglokomotive f\u00fcr den automatisierten Regelbetrieb umger\u00fcstet: DB Cargo hat im Werk K\u00f6ln-Gremberg die erste Strecken-Lok mit modernsten Technologien f\u00fcr Automatic Train<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":4797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1573,1666,1569],"tags":[],"class_list":["post-4796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionen","category-rubriken","category-logistik-spedition"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Erstmals wurde in Europa eine G\u00fcterzuglokomotive f\u00fcr den automatisierten Regelbetrieb umger\u00fcstet: DB Cargo hat im Werk K\u00f6ln-Gremberg die erste Strecken-Lok mit modernsten Technologien f\u00fcr Automatic Train [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T15:15:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DB_Cargo_4.7.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1294\" \/>\n\t<meta property=\"og:image:height\" content=\"928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Fritz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Fritz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/\"},\"author\":{\"name\":\"Danny Fritz\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\"},\"headline\":\"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb\",\"datePublished\":\"2025-07-04T15:15:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DB_Cargo_4.7.25.jpg\",\"articleSection\":[\"Regionen\",\"Rubriken\",\"Spedition &amp; Logistik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/\",\"name\":\"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DB_Cargo_4.7.25.jpg\",\"datePublished\":\"2025-07-04T15:15:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DB_Cargo_4.7.25.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/DB_Cargo_4.7.25.jpg\",\"width\":1294,\"height\":928},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/07\\\/04\\\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\",\"name\":\"Danny Fritz\",\"sameAs\":[\"https:\\\/\\\/dashboard.brand-architecture.at\"],\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/author\\\/danny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/","og_locale":"de_DE","og_type":"article","og_title":"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb - ITJ | International Transport Journal","og_description":"Erstmals wurde in Europa eine G\u00fcterzuglokomotive f\u00fcr den automatisierten Regelbetrieb umger\u00fcstet: DB Cargo hat im Werk K\u00f6ln-Gremberg die erste Strecken-Lok mit modernsten Technologien f\u00fcr Automatic Train [\u2026]","og_url":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2025-07-04T15:15:58+00:00","og_image":[{"width":1294,"height":928,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DB_Cargo_4.7.25.jpg","type":"image\/jpeg"}],"author":"Danny Fritz","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Danny Fritz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/"},"author":{"name":"Danny Fritz","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876"},"headline":"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb","datePublished":"2025-07-04T15:15:58+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DB_Cargo_4.7.25.jpg","articleSection":["Regionen","Rubriken","Spedition &amp; Logistik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/","url":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/","name":"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DB_Cargo_4.7.25.jpg","datePublished":"2025-07-04T15:15:58+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DB_Cargo_4.7.25.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/DB_Cargo_4.7.25.jpg","width":1294,"height":928},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/de\/2025\/07\/04\/db-cargo-ruestet-europaweit-erste-lok-fuer-automatisierten-betrieb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/de\/"},{"@type":"ListItem","position":2,"name":"DB Cargo r\u00fcstet europaweit erste Lok f\u00fcr automatisierten Betrieb"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/de\/#website","url":"https:\/\/transportjournal.com\/de\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/de\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876","name":"Danny Fritz","sameAs":["https:\/\/dashboard.brand-architecture.at"],"url":"https:\/\/transportjournal.com\/de\/author\/danny\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/4796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/comments?post=4796"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/4796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/media\/4797"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/media?parent=4796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/categories?post=4796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/tags?post=4796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}