{"id":4176,"date":"2025-11-30T17:39:26","date_gmt":"2025-11-30T16:39:26","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/"},"modified":"2025-11-30T17:39:26","modified_gmt":"2025-11-30T16:39:26","slug":"panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/","title":{"rendered":"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen"},"content":{"rendered":"<h5><strong>Passgenau und bereits vor Baubeginn vollst\u00e4ndig vermietet: Im neuen Gewerbegebiet \u201eKoppelknechtsdamm\u201c in Garbsen realisiert Panattoni eine moderne Build-to-suit-Immobilie (BTS). Das Projekt wird individuell f\u00fcr die spezifischen Anforderungen des zuk\u00fcnftigen Mieters entwickelt und st\u00e4rkt die Stadt Garbsen als Wirtschaftsstandort im Gro\u00dfraum Hannover. Es ist bereits die dritte BTS-Immobilie, die Panattoni in der Gemeinde realisiert. <\/strong><\/h5>\n<p>(Hamburg\/Garbsen) Die Logistikfl\u00e4che von rund 12.100 m\u00b2, die B\u00fcro- und Sozialfl\u00e4chen mit 1.670 m\u00b2 sowie die Freilagerfl\u00e4che von 1.000 m\u00b2 werden optimal auf die Bed\u00fcrfnisse des zuk\u00fcnftigen langfristigen Mieters zugeschnitten. Eine lichte Hallenh\u00f6he von 12,20 m und 50 Pkw-Stellpl\u00e4tzen runden das Angebot ab. Dar\u00fcber hinaus sorgt die N\u00e4he zu den Autobahnen A2 und A7, zum Flughafen Hannover Airport und zum G\u00fcterverkehrszentrum Hannover-Lehrte f\u00fcr eine ideale Anbindung des Standorts.<\/p>\n<p>\u201eMit der Entwicklung dieser ma\u00dfgeschneiderten Logistikimmobilie setzen wir ein weiteres Zeichen f\u00fcr die wirtschaftliche St\u00e4rke des Standorts Garbsen und der Region Hannover\u201c, sagt Fred-Markus Bohne, Managing Partner bei Panattoni Deutschland und \u00d6sterreich. \u201eUnser Fokus liegt darauf, innovative Immobilienl\u00f6sungen zu realisieren, die sowohl den individuellen Bed\u00fcrfnissen der Unternehmen als auch den h\u00f6chsten Nachhaltigkeits-Kriterien entsprechen. Die hervorragende Zusammenarbeit mit der Stadt Garbsen und der Wirtschaftsf\u00f6rderung hat gezeigt, wie wichtig starke Partnerschaften f\u00fcr die erfolgreiche Entwicklung solcher Projekte sind.\u201c<\/p>\n<h5><strong>Hohe Nachhaltigkeitsstandards im Fokus\u00a0 \u00a0<\/strong><\/h5>\n<p>Das Projekt soll nachhaltig gebaut und nach den Kriterien der Deutschen Gesellschaft f\u00fcr Nachhaltiges Bauen e.V. (DGNB) zertifiziert werden. Panattoni strebt dabei das DGNB Gold Zertifikat an. Zu den umweltfreundlichen Ma\u00dfnahmen geh\u00f6ren eine Photovoltaikanlage auf dem Dach, eine Luft-Wasser-W\u00e4rmepumpe sowie die Nutzung von Regenwasser. Dar\u00fcber hinaus wird eine gro\u00dfz\u00fcgige Well-Being-Area f\u00fcr die Mitarbeitenden geschaffen, um eine angenehme Arbeitsumgebung zu gew\u00e4hrleisten.<\/p>\n<p>\u201eDie Ansiedlung durch Panattoni als aktivster Industrieentwickler Europas zeigt, wie attraktiv Garbsen als Wirtschaftsstandort ist\u201c, sagt Claudio Provenzano, B\u00fcrgermeister der Stadt Garbsen. \u201eDas Investment passt hervorragend in die strategische Ausrichtung der Stadt und schafft neue Arbeitspl\u00e4tze.\u201c Die Fertigstellung der Immobilie ist f\u00fcr Oktober 2026 geplant. Die Vermittlung des Mieters erfolgte durch BNP Paribas Real Estate.<\/p>\n<p>Foto: \u00a9 Panattoni<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passgenau und bereits vor Baubeginn vollst\u00e4ndig vermietet: Im neuen Gewerbegebiet \u201eKoppelknechtsdamm\u201c in Garbsen realisiert Panattoni eine moderne Build-to-suit-Immobilie (BTS). Das Projekt wird individuell f\u00fcr die spezifischen<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":4106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1573,1569],"tags":[],"class_list":["post-4176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionen","category-logistik-spedition"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Passgenau und bereits vor Baubeginn vollst\u00e4ndig vermietet: Im neuen Gewerbegebiet \u201eKoppelknechtsdamm\u201c in Garbsen realisiert Panattoni eine moderne Build-to-suit-Immobilie (BTS). Das Projekt wird individuell f\u00fcr die spezifischen [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-30T16:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Panattoni_30.11.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1393\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Fritz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Fritz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/\"},\"author\":{\"name\":\"Danny Fritz\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\"},\"headline\":\"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen\",\"datePublished\":\"2025-11-30T16:39:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/\"},\"wordCount\":358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/Panattoni_30.11.25.jpg\",\"articleSection\":[\"Regionen\",\"Spedition &amp; Logistik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/\",\"name\":\"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/Panattoni_30.11.25.jpg\",\"datePublished\":\"2025-11-30T16:39:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/Panattoni_30.11.25.jpg\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/Panattoni_30.11.25.jpg\",\"width\":1393,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2025\\\/11\\\/30\\\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\",\"name\":\"Danny Fritz\",\"sameAs\":[\"https:\\\/\\\/dashboard.logismedia.group\"],\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/author\\\/danny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/","og_locale":"de_DE","og_type":"article","og_title":"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen - ITJ | International Transport Journal","og_description":"Passgenau und bereits vor Baubeginn vollst\u00e4ndig vermietet: Im neuen Gewerbegebiet \u201eKoppelknechtsdamm\u201c in Garbsen realisiert Panattoni eine moderne Build-to-suit-Immobilie (BTS). Das Projekt wird individuell f\u00fcr die spezifischen [\u2026]","og_url":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2025-11-30T16:39:26+00:00","og_image":[{"width":1393,"height":780,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Panattoni_30.11.25.jpg","type":"image\/jpeg"}],"author":"Danny Fritz","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Danny Fritz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/"},"author":{"name":"Danny Fritz","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876"},"headline":"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen","datePublished":"2025-11-30T16:39:26+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/"},"wordCount":358,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"image":{"@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Panattoni_30.11.25.jpg","articleSection":["Regionen","Spedition &amp; Logistik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/","url":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/","name":"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#primaryimage"},"image":{"@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#primaryimage"},"thumbnailUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Panattoni_30.11.25.jpg","datePublished":"2025-11-30T16:39:26+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#primaryimage","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Panattoni_30.11.25.jpg","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Panattoni_30.11.25.jpg","width":1393,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/de\/2025\/11\/30\/panattoni-errichtet-bereits-vermietete-logistikimmobilie-in-garbsen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/de\/"},{"@type":"ListItem","position":2,"name":"Panattoni errichtet bereits vermietete Logistikimmobilie in Garbsen"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/de\/#website","url":"https:\/\/transportjournal.com\/de\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/de\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876","name":"Danny Fritz","sameAs":["https:\/\/dashboard.logismedia.group"],"url":"https:\/\/transportjournal.com\/de\/author\/danny\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/4176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/comments?post=4176"}],"version-history":[{"count":0,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/4176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/media\/4106"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/media?parent=4176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/categories?post=4176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/tags?post=4176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}