{"id":16817,"date":"2020-04-06T09:48:01","date_gmt":"2020-04-06T07:48:01","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/"},"modified":"2025-12-15T12:25:22","modified_gmt":"2025-12-15T11:25:22","slug":"mit-nexiga-geodaten-neue-kurier-express-post-services-planen","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/","title":{"rendered":"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen"},"content":{"rendered":"<p>Nexiga - Partner des Kurier-Express-Post Corona Lagezentrums, bietet kostenfreien Zugang zu Geodaten. Auf Basis dieser Informationen k\u00f6nnen neue Services, beispielsweise f\u00fcr Risikogruppen, geplant werden.<\/p>\n<p>(Bonn, 06.04.2020) Das Kurier-Express-Post Corona Lagezentrum wurde vom Bundesverband der Kurier-Express-Post-Dienste e.V. (BdKEP)\u00a0aktiviert und\u00a0unterst\u00fctzt Unternehmen der Branche bei der Bew\u00e4ltigung der Krise. Nexiga, Anbieter von Geol\u00f6sungen f\u00fcr die Logistik, unterst\u00fctzt das Lagezentrum mit einem kostenfreien Zugang f\u00fcr Geodaten.<\/p>\n<p>Vor allem \u00e4ltere Menschen sind von den Auswirkungen des Coronavirus stark betroffen. Sie haben h\u00e4ufiger als j\u00fcngere Menschen einen schweren Krankheitsverlauf. Um das Risiko der Ansteckung zu senken, ist soziale Distanz hier besonders wichtig. Im Gegenzug braucht es Hilfsangebote, die diese Situation f\u00fcr sie ertr\u00e4glicher machen. Ma\u00dfnahmen zur Unterst\u00fctzung sind wirksam umsetzbar, wenn Wohnquartiere mit einem hohen Anteil an \u00e4lterer Bev\u00f6lkerung bekannt sind. Beispielsweise die Versorgung mit Waren des t\u00e4glichen Bedarfs oder andere Hilfen im Alltag k\u00f6nnen so besser geplant werden.<\/p>\n<p><strong>Nexiga stellt interaktive Karten kostenfrei bereit<br \/>\n<\/strong>Nexiga - Partner des Bundesverband der Kurier-Express-Post-Dienste e.V. (BdKEP) Corona Lagezentrums, stellt bundesweite interaktive Karten zur Darstellung der Bev\u00f6lkerungsstruktur bis auf Ebene der Wohnquartiere bereit. In einem Wohnquartier befinden sich maximal 500 Haushalte. Der Zugang ist f\u00fcr den Zeitraum der Krise kostenfrei. Es k\u00f6nnen unter anderem der Anteil und die Anzahl der B\u00fcrger unterschiedlicher Altersklassen in der Bev\u00f6lkerung visualisiert werden. Auf Basis dieser Informationen haben Einzelhandel in Kombination mit Kurier- und Postdiensten M\u00f6glichkeiten, Dienstleistungen gezielt zu entwickeln. Beispielsweise k\u00f6nnen das f\u00fcr \u00e4ltere B\u00fcrger Einkaufsdienste f\u00fcr Lebensmittel sein, f\u00fcr j\u00fcngere Familien die Versorgung mit neuen Fr\u00fchjahrsschuhen f\u00fcr die Kinder.<\/p>\n<p><strong>Demo-Webtool f\u00fcr alle Regionen verf\u00fcgbar<br \/>\n<\/strong>Ein Demo-Webtool f\u00fcr das Gebiet der Stadt K\u00f6ln zeigt die umfangreichen M\u00f6glichkeiten der Anwendung beispielhaft. Zugangsdaten f\u00fcr den kostenfreien Zugang zu Daten anderer Regionen k\u00f6nnen unkompliziert angefordert werden.<\/p>\n<p>\u201eWir freuen uns, wenn unsere Daten und unser Fachwissen bei der Bew\u00e4ltigung der Krise helfen k\u00f6nnen. Wir sind \u00fcberzeugt, dass Geodaten und sozio-demografische Merkmale B\u00fcrgern, Einzelhandel und KEP Diensten dabei helfen, die Krise bestm\u00f6glich zu meistern. Wir sehen parallel dazu viele Potentiale, wie diese Daten die Beteiligten bei der Digitalisierung ihrer Gesch\u00e4ftsmodelle unterst\u00fctzen k\u00f6nnen\u201c, sagt CEO Dirk Schneider, Nexiga GmbH<\/p>\n<p>\u201eIch freue mich, dass Nexiga \u00fcber das KEP Corona Lagezentrum diese wichtigen Daten w\u00e4hrend der Corona Krise kostenfrei zug\u00e4nglich macht. Der Markt ist in einem starken Wandel. In diesen turbulenten Zeiten k\u00f6nnen \u00fcber das Tool Beteiligte zusammenfinden, die in normalen Zeiten nie zusammengefunden h\u00e4tten. Das schafft trotz der Krise Raum f\u00fcr Innovationen. Im Idealfall reicht die Dynamik dann auch \u00fcber das Krisenende hinaus.\u201c\u00a0so Andreas Schumann, Vorsitzender des BdKEP und Initiator des KEP Corona Lagezentrums.<\/p>\n<p>Foto: S.Hermann &amp; F. Richter auf Pixabay<\/p>\n<p><a href=\"https:\/\/www.nexiga.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.nexiga.com\u00a0\u00a0\u00a0\u00a0<\/a><a href=\"https:\/\/bdkep.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.bdkep.de<\/a>\u00a0\u00a0\u00a0 <a href=\"https:\/\/kep-corona.de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/kep-corona.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nexiga - Partner des Kurier-Express-Post Corona Lagezentrums, bietet kostenfreien Zugang zu Geodaten. Auf Basis dieser Informationen k\u00f6nnen neue Services, beispielsweise f\u00fcr Risikogruppen, geplant werden. (Bonn, 06.04.2020)<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1568,1573,1569],"tags":[],"class_list":["post-16817","post","type-post","status-publish","format-standard","hentry","category-bahn-binnenschifffahrt-strasse","category-regionen","category-logistik-spedition"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mit Nexiga Geodaten neue Kurier-Express-Post Services planen - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Nexiga - Partner des Kurier-Express-Post Corona Lagezentrums, bietet kostenfreien Zugang zu Geodaten. Auf Basis dieser Informationen k\u00f6nnen neue Services, beispielsweise f\u00fcr Risikogruppen, geplant werden. (Bonn, 06.04.2020) [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-06T07:48:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Nexiga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1735\" \/>\n\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Fritz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Fritz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/\"},\"author\":{\"name\":\"Danny Fritz\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\"},\"headline\":\"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen\",\"datePublished\":\"2020-04-06T07:48:01+00:00\",\"dateModified\":\"2025-12-15T11:25:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/\"},\"wordCount\":491,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"articleSection\":[\"Intermodal \\\/ Stra\u00dfe\",\"Regionen\",\"Spedition &amp; Logistik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/\",\"name\":\"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\"},\"datePublished\":\"2020-04-06T07:48:01+00:00\",\"dateModified\":\"2025-12-15T11:25:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/06\\\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\",\"name\":\"Danny Fritz\",\"sameAs\":[\"https:\\\/\\\/dashboard.logismedia.group\"],\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/author\\\/danny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/","og_locale":"de_DE","og_type":"article","og_title":"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen - ITJ | International Transport Journal","og_description":"Nexiga - Partner des Kurier-Express-Post Corona Lagezentrums, bietet kostenfreien Zugang zu Geodaten. Auf Basis dieser Informationen k\u00f6nnen neue Services, beispielsweise f\u00fcr Risikogruppen, geplant werden. (Bonn, 06.04.2020) [\u2026]","og_url":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-04-06T07:48:01+00:00","article_modified_time":"2025-12-15T11:25:22+00:00","og_image":[{"width":1735,"height":896,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Nexiga.jpg","type":"image\/jpeg"}],"author":"Danny Fritz","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Danny Fritz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/"},"author":{"name":"Danny Fritz","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876"},"headline":"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen","datePublished":"2020-04-06T07:48:01+00:00","dateModified":"2025-12-15T11:25:22+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/"},"wordCount":491,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"articleSection":["Intermodal \/ Stra\u00dfe","Regionen","Spedition &amp; Logistik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/","url":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/","name":"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/#website"},"datePublished":"2020-04-06T07:48:01+00:00","dateModified":"2025-12-15T11:25:22+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/de\/2020\/04\/06\/mit-nexiga-geodaten-neue-kurier-express-post-services-planen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/de\/"},{"@type":"ListItem","position":2,"name":"Mit Nexiga Geodaten neue Kurier-Express-Post Services planen"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/de\/#website","url":"https:\/\/transportjournal.com\/de\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/de\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876","name":"Danny Fritz","sameAs":["https:\/\/dashboard.logismedia.group"],"url":"https:\/\/transportjournal.com\/de\/author\/danny\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/16817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/comments?post=16817"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/16817\/revisions"}],"predecessor-version":[{"id":30366,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/16817\/revisions\/30366"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/media?parent=16817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/categories?post=16817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/tags?post=16817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}