{"id":16801,"date":"2020-04-14T18:30:11","date_gmt":"2020-04-14T16:30:11","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/"},"modified":"2025-12-15T12:25:20","modified_gmt":"2025-12-15T11:25:20","slug":"schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel","status":"publish","type":"post","link":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/","title":{"rendered":"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel"},"content":{"rendered":"<p>Zwischen China und dem duisport verkehren rund 40 Z\u00fcge w\u00f6chentlich. Nachdem die Corona-Krise in der Region Wuhan begonnen hat, kommen nun auch wieder Z\u00fcge von dort nach Duisburg.<\/p>\n<p>(Duisburg, 14.04.2020) Der Warenverkehr aus China steigt wieder deutlich an: Gemeinsam mit NRW-Verkehrsminister Hendrik W\u00fcst, dem Generalkonsul der Volksrepublik China in D\u00fcsseldorf, Feng Haiyang sowie Dr. Roland P\u00fctz, Gesch\u00e4ftsf\u00fchrer Hutchison Ports Duisburg, empfing duisport-Vorstandsvorsitzender Erich Staake einen der ersten G\u00fcterz\u00fcge aus Wuhan nach Ausbruch der Corona- Pandemie auf dem Gel\u00e4nde des Hutchison Ports Duisburg (ehemals DeCeTe).<\/p>\n<p>Chinas Industrieproduktion findet nach Eind\u00e4mmung der Corona-Epidemie wieder zu alter St\u00e4rke zur\u00fcck. Rund zwei Monate waren die Millionenstadt Wuhan, die seit 1982 Partnerstadt Duisburgs ist sowie die gesamte Provinz Hubei f\u00fcr G\u00fcter- und Personenverkehre abgeriegelt. Wuhan gilt als Ausgangspunkt der weltweiten Corona-Pandemie.<\/p>\n<p>Auch der Duisburger Hafen war von den Auswirkungen der massiven Beschr\u00e4nkungen in der Provinz Hubei betroffen und hat vor allem im M\u00e4rz einen deutlichen R\u00fcckgang im Segment der G\u00fcterverkehre aus China und anderen asiatischen L\u00e4ndern, wie zum Beispiel S\u00fcdkorea, verzeichnen m\u00fcssen.<\/p>\n<p>Rund 40 Z\u00fcge verkehren nun wieder w\u00f6chentlich zwischen Duisburg und verschiedenen Destinationen in China. W\u00e4hrend der Corona-Krise in China gab es hier sp\u00fcrbare R\u00fcckg\u00e4nge. Die H\u00e4lfte des Seeverkehres mit China kam zwischenzeitlich zum Erliegen. Seit Aufhebung der Abriegelungen nimmt Chinas Wirtschaft jedoch wieder deutlich Fahrt auf.<\/p>\n<p>\u201eDer Ausbruch der Corona-Pandemie hat unser Land schwer getroffen. Dennoch sind wir zuversichtlich, dass der Alltag langsam zur\u00fcckkehren wird. Die Wiederaufnahme des interkontinentalen Bahnverkehres aus der Provinz Hubei ist dabei ein wichtiger Baustein sowie zuverl\u00e4ssige Option f\u00fcr Industrie und Handel. Wir setzen auf unsere starken Verbindungen zu duisport als bedeutende Logistikdrehscheibe in Zentraleuropa\u201c, sagt Feng Haiyang, Generalkonsul der Volksrepublik China in D\u00fcsseldorf.<\/p>\n<p><strong>Warenverkehr aus der betroffenen Region Wuhan wieder aufgenommen<br \/>\n<\/strong>\u201eNach 76 Tagen Isolation wurde das Ausreiseverbot in der Stadt Wuhan am 24. M\u00e4rz aufgehoben. Das Ende des Lockdowns in dieser von der Corona-Krise so stark betroffenen Stadt hat auch symbolische Bedeutung. Wir alle wissen, dass uns die Corona-Krise in Nordrhein-Westfalen wie in China noch begleiten wird. Der Kampf gegen das Virus ist noch nicht vorbei, aber dass der Schienenverkehr zwischen Asien und Europa wieder reibungslos funktioniert, ist ein gutes Zeichen der Normalisierung\u201c, erkl\u00e4rte Hendrik W\u00fcst, Verkehrsminister des Landes Nordrhein-Westfalen.<\/p>\n<p>\u201eSchon bald werden wir wieder das alte Niveau im Warenaustausch mit China erreicht haben. Der Duisburger Hafen sp\u00fcrt die Folgen der Pandemie zwar mit einer gewissen Verz\u00f6gerung, dennoch gehe ich von eindeutigen Nachholeffekten im China-Gesch\u00e4ft aus\u201c, erkl\u00e4rt duisport-Vorstandsvorsitzender Erich Staake. \u201eBereits in der zweiten Aprilh\u00e4lfte rechnen wir mit einem deutlich erh\u00f6hten Warenaufkommen, darauf reagieren wir als duisport-Gruppe mit gesteigerten Terminalkapazit\u00e4ten und kurzfristigen Lagerl\u00f6sungen. Unser Netzwerk funktioniert auch in Krisenzeiten\u201c, erg\u00e4nzt Staake.<\/p>\n<p><em>Foto\/Bildlegende: Social Distancing zu Zeiten von Corona: Dr. Roland P\u00fctz, Gesch\u00e4ftsf\u00fchrer Hutchison Ports Duisburg; Erich Staake, Vorstandsvorsitzender der duisport-Gruppe; Hendrik W\u00fcst, Verkehrsminister des Landes Nordrhein-Westfalen; Feng Haiyang, Generalkonsul der Volksrepublik China in D\u00fcsseldorf auf dem Gel\u00e4nde des Hutchison Ports Duisburg (ehemals DeCeTe) I \u00a9 duisport \/ dws Werbeagentur GmbH<\/em><\/p>\n<p><a href=\"https:\/\/www.duisport.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.duisport.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zwischen China und dem duisport verkehren rund 40 Z\u00fcge w\u00f6chentlich. Nachdem die Corona-Krise in der Region Wuhan begonnen hat, kommen nun auch wieder Z\u00fcge von dort<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1573,1571,1569],"tags":[],"class_list":["post-16801","post","type-post","status-publish","format-standard","hentry","category-regionen","category-schiffahrt","category-logistik-spedition"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel - ITJ | International Transport Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel - ITJ | International Transport Journal\" \/>\n<meta property=\"og:description\" content=\"Zwischen China und dem duisport verkehren rund 40 Z\u00fcge w\u00f6chentlich. Nachdem die Corona-Krise in der Region Wuhan begonnen hat, kommen nun auch wieder Z\u00fcge von dort [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/\" \/>\n<meta property=\"og:site_name\" content=\"ITJ | International Transport Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-14T16:30:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:25:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Duisport.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1387\" \/>\n\t<meta property=\"og:image:height\" content=\"937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Fritz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Fritz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/\"},\"author\":{\"name\":\"Danny Fritz\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\"},\"headline\":\"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel\",\"datePublished\":\"2020-04-14T16:30:11+00:00\",\"dateModified\":\"2025-12-15T11:25:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/\"},\"wordCount\":541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"articleSection\":[\"Regionen\",\"Schifffahrt &amp; H\u00e4fen\",\"Spedition &amp; Logistik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/\",\"name\":\"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel - ITJ | International Transport Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\"},\"datePublished\":\"2020-04-14T16:30:11+00:00\",\"dateModified\":\"2025-12-15T11:25:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/2020\\\/04\\\/14\\\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"name\":\"ITJ | International Transport Journal\",\"description\":\"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"contentUrl\":\"https:\\\/\\\/transportjournal.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/Logo_ITJ.png\",\"width\":799,\"height\":326,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/56456496\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/logismediagroup\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LogiamediaGroupAG\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\",\"name\":\"Danny Fritz\",\"sameAs\":[\"https:\\\/\\\/dashboard.logismedia.group\"],\"url\":\"https:\\\/\\\/transportjournal.com\\\/de\\\/author\\\/danny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel - ITJ | International Transport Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/","og_locale":"de_DE","og_type":"article","og_title":"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel - ITJ | International Transport Journal","og_description":"Zwischen China und dem duisport verkehren rund 40 Z\u00fcge w\u00f6chentlich. Nachdem die Corona-Krise in der Region Wuhan begonnen hat, kommen nun auch wieder Z\u00fcge von dort [\u2026]","og_url":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/","og_site_name":"ITJ | International Transport Journal","article_published_time":"2020-04-14T16:30:11+00:00","article_modified_time":"2025-12-15T11:25:20+00:00","og_image":[{"width":1387,"height":937,"url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/12\/Duisport.jpg","type":"image\/jpeg"}],"author":"Danny Fritz","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Danny Fritz","Gesch\u00e4tzte Lesezeit":"3\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/#article","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/"},"author":{"name":"Danny Fritz","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876"},"headline":"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel","datePublished":"2020-04-14T16:30:11+00:00","dateModified":"2025-12-15T11:25:20+00:00","mainEntityOfPage":{"@id":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/"},"wordCount":541,"commentCount":0,"publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"articleSection":["Regionen","Schifffahrt &amp; H\u00e4fen","Spedition &amp; Logistik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/","url":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/","name":"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel - ITJ | International Transport Journal","isPartOf":{"@id":"https:\/\/transportjournal.com\/de\/#website"},"datePublished":"2020-04-14T16:30:11+00:00","dateModified":"2025-12-15T11:25:20+00:00","breadcrumb":{"@id":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/transportjournal.com\/de\/2020\/04\/14\/schienenverkehr-staerkt-duisport-als-europaeisches-hub-im-china-handel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transportjournal.com\/de\/"},{"@type":"ListItem","position":2,"name":"Schienenverkehr st\u00e4rkt duisport als europ\u00e4isches Hub im China-Handel"}]},{"@type":"WebSite","@id":"https:\/\/transportjournal.com\/de\/#website","url":"https:\/\/transportjournal.com\/de\/","name":"ITJ | International Transport Journal","description":"Stay informed with the latest global news from the transport, logistics, and supply chain industries. Transport Journal delivers expert insights, analysis, and updates across shipping, aviation, intermodal, and forwarding.","publisher":{"@id":"https:\/\/transportjournal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transportjournal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/transportjournal.com\/de\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/transportjournal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","contentUrl":"https:\/\/transportjournal.com\/wp-content\/uploads\/sites\/2\/2025\/09\/Logo_ITJ.png","width":799,"height":326,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/transportjournal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/56456496\/admin\/dashboard\/","https:\/\/www.instagram.com\/logismediagroup\/","https:\/\/www.youtube.com\/@LogiamediaGroupAG"]},{"@type":"Person","@id":"https:\/\/transportjournal.com\/de\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876","name":"Danny Fritz","sameAs":["https:\/\/dashboard.logismedia.group"],"url":"https:\/\/transportjournal.com\/de\/author\/danny\/"}]}},"_links":{"self":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/16801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/comments?post=16801"}],"version-history":[{"count":1,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/16801\/revisions"}],"predecessor-version":[{"id":30358,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/posts\/16801\/revisions\/30358"}],"wp:attachment":[{"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/media?parent=16801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/categories?post=16801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportjournal.com\/de\/wp-json\/wp\/v2\/tags?post=16801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}